{"id":10147,"date":"2020-06-03T00:51:00","date_gmt":"2020-06-03T03:51:00","guid":{"rendered":"http:\/\/gremioseguridad.com\/electronica\/?p=10147"},"modified":"2020-07-01T00:55:18","modified_gmt":"2020-07-01T03:55:18","slug":"hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7","status":"publish","type":"post","link":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/","title":{"rendered":"Hanwha Techwin: nuevo nivel con chipset Wisenet 7"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Wisenet 7, fabricado directamente por la compa\u00f1\u00eda en Corea, cuenta con Inteligencia Artificial, ideal para capturar los diferentes atributos de cualquier objeto, incluyendo personas, veh\u00edculos, caras y matr\u00edculas.<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Hanwha Techwin, un l\u00edder global en soluciones de videovigilancia, ha anunciado el lanzamiento del nuevo chipset Wisenet 7, la m\u00e1s reciente adici\u00f3n a la familia de procesadores de imagen de Hanwha Techwin. Desde Corea, con m\u00e1s de 30 a\u00f1os de tradici\u00f3n en innovaci\u00f3n, Wisenet 7 incorpora algoritmos de Inteligencia Artificial (AI por sus siglas en ingl\u00e9s), WDR avanzado y calidad de im\u00e1genes con ultra alta definici\u00f3n.<\/p>\n\n\n\n<p><strong>Anal\u00edticas basadas en AI<\/strong><\/p>\n\n\n\n<p><em>\u201c<\/em>Latinoam\u00e9rica es reconocida por ser una regi\u00f3n que adopta nuevas tecnolog\u00edas de forma r\u00e1pida y en ser los primeros en implementar anal\u00edticas de la pr\u00f3xima generaci\u00f3n como la AI<em>\u201d,<\/em> destaca Jason de Souza, director de Ventas para Am\u00e9rica Latina.<\/p>\n\n\n\n<p>La detecci\u00f3n de movimiento de los modelos convencionales estaba basada en el movimiento de p\u00edxeles, causando frecuentes alarmas de eventos falsos. Con la tecnolog\u00eda de detecci\u00f3n de objetos basada en AI de Wisenet7, las c\u00e1maras ahora reconocen y clasifican los atributos de los objetos, incluidas las personas, rostros, veh\u00edculos y placas. Esto reduce dr\u00e1sticamente las falsas alarmas de eventos y conduce a operaciones m\u00e1s eficientes.<\/p>\n\n\n\n<p>Las c\u00e1maras equipadas con Wisenet7 de la serie P cuentan con la funci\u00f3n BestShot, garantizando que solo las im\u00e1genes m\u00e1s adecuadas de objetos clasificados se env\u00eden al servidor back-end y reduciendo el ancho de banda.<\/p>\n\n\n\n<p><strong>Anal\u00edticas mejoradas para la \u201cnueva normalidad\u201d<\/strong><\/p>\n\n\n\n<p>Muchos pa\u00edses ya est\u00e1n empezando a regresar a una \u201cnueva normalidad\u201d, en la que inevitablemente, las reglas de distanciamiento social tendr\u00e1n que permanecer, y esto probablemente signifique que solo un n\u00famero espec\u00edfico de personas podr\u00e1n estar en un \u00e1rea controlada en cualquier momento. Para ello Wisenet7 est\u00e1 preparado con anal\u00edticas mejoradas para otorgar la m\u00e1xima precisi\u00f3n en conteo de personas y mapa de calor para el aforo en establecimientos.<\/p>\n\n\n\n<p><strong>Seguridad cibern\u00e9tica mejorada<\/strong><\/p>\n\n\n\n<p>Desde el momento en que un dispositivo con Wisenet 7 est\u00e1 conectado a una red, varios filtros de seguridad impiden que agentes externos ingresen al chipset de la c\u00e1mara o a su memoria interna.<\/p>\n\n\n\n<p>Hanwha Techwin estableci\u00f3 su propio sistema de emisi\u00f3n de certificados de dispositivo para incorporar certificados en el producto, no solo en el progreso del desarrollo, sino tambi\u00e9n en el de la fabricaci\u00f3n.<\/p>\n\n\n\n<p><strong>WDR de clase mundial<\/strong><\/p>\n\n\n\n<p>El rango din\u00e1mico se ha maximizado para reducir el ruido al componer los fotogramas m\u00faltiples filmados en exposiciones variables. La tecnolog\u00eda de an\u00e1lisis de escena recientemente adoptada ayuda a la c\u00e1mara a producir una imagen WDR optimizada, capaz de capturar im\u00e1genes de ultra alta definici\u00f3n a\u00fan en escenas que contienen una mezcla desafiante de \u00e1reas brillantes y oscuras.<\/p>\n\n\n\n<p><strong>Rendimiento mejorado con poca luz<\/strong><\/p>\n\n\n\n<p>Wisenet7 analiza y filtra los datos de objetos en movimiento en entornos con poca luz, al utilizar un nuevo algoritmo adaptativo de ruido para reducir de manera significativa el ruido del sensor. Estas im\u00e1genes m\u00e1s claras mejoran los resultados para el rendimiento del reconocimiento de objetos con poca luz.<\/p>\n\n\n\n<p><strong>B\u00fasquedas forenses por atributos.<\/strong><\/p>\n\n\n\n<p>Los metadatos que incluyen informaci\u00f3n de atributos, ya sea, en el caso de personas, colores o ropa superior\/inferior y gafas, as\u00ed como la marca y color para el caso de los veh\u00edculos, reducen significativamente el tiempo de b\u00fasqueda de todo el video.<\/p>\n\n\n\n<p><strong>Correcci\u00f3n de distorsi\u00f3n de lente mejorada<\/strong><\/p>\n\n\n\n<p>Wisenet7 corrige la distorsi\u00f3n causada por lentes de gran \u00e1ngulo. Esto ofrece una calidad de video que representa de forma m\u00e1s clara c\u00f3mo los seres humanos ven a trav\u00e9s de un amplio campo de visi\u00f3n.<\/p>\n\n\n\n<p>Te invitamos a seguir a Hanwha Techwin en <a href=\"https:\/\/l.facebook.com\/l.php?u=https%3A%2F%2Ftwitter.com%2FHanwha_Latam%3Ffbclid%3DIwAR0TzC7FQhsQg9_K27VH4HFe5qxPVmyauCmUM449TVzjyy48-9aBIKJsbtA&amp;h=AT3kLM08tHlmnyr2-mrJWkU1xJ_bqe1Ek_v9MoXYxdWuj09ufHhQnZLQLCyeGwgosmkTfK4uPWM_lW35N-pPMD3KmAwFJk5AraL4-jHBxR-JWrAiqAWdUvem5xk4KLVrtJATkuwY\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Twitter<\/strong><\/a><strong>, <\/strong><a href=\"https:\/\/www.facebook.com\/HanwhaTechwinLatam\/\"><strong>Facebook<\/strong><\/a><strong>, <\/strong><a href=\"https:\/\/l.facebook.com\/l.php?u=https%3A%2F%2Fwww.instagram.com%2Fhanwhatechwinlatam%2F%3Ffbclid%3DIwAR39I_2O5x_xbS2wdF0oV9r9SXPKGJi2VqdWSh0asZcCOh3RjWTEHSBAiXA&amp;h=AT1KpYNakHqG3fKkkCa56W03mjsK1BsOwypcvmVzc2CTpQbpDyEugtJc3OeQ-kNdBglaksfzPdxuu8L2ooTYz95BoWK5lQWFQnAA57aDque4lRDfya549_jphSmatKr9TbS5TvwM\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Instagram<\/strong><\/a><a href=\"https:\/\/l.facebook.com\/l.php?u=https%3A%2F%2Fwww.instagram.com%2Fhanwhatechwinlatam%2F%3Ffbclid%3DIwAR0BVrkCoZ0hmeHfm8vrp-0mC4LZjPSh6bXLXL2g1G0_W6jwf8qOC4AakyU&amp;h=AT3cd3beNiPIJx5_M5xamqk-fExa8LiKFIhtvdRZsZ1Wsj6E6cI4QvXgn9P7830V0jJXPgHRI8-bYi5k12w6KJvK6dNz9VYI_QXSARzzrL-kI82rRt90WctI3uK6VcQNoTt_a-jD\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>,<\/strong><\/a><a href=\"https:\/\/l.facebook.com\/l.php?u=https%3A%2F%2Fwww.linkedin.com%2Fcompany%2Fhanwha-techwin-latam%3Ffbclid%3DIwAR0BAX3sfuM5dkzrRxXWn0X8JCLK311PLNeh3eQY3TEQn-01vaSaUUhTqLY&amp;h=AT3EEQ-0UuP70ScEUPAjbogQ1YDNtyzPIJin64rh5GM3ylVEsUFufsUzWcXvz3OpJUlkYdcxJ5Isk0QsOIk3c98YNugsYYvs-5-znlyCUx0RJxTakArTChcteM4J362EdgtDL_wV\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>LinkedIn<\/strong><\/a>y<a href=\"https:\/\/l.facebook.com\/l.php?u=https%3A%2F%2Fwww.youtube.com%2Fchannel%2FUCAHmzWY38zXyso5itpbl3YA%3Ffbclid%3DIwAR3cmXHmqOMHcH9oWT-NvbxkdK6QmDPySF7hsIrc3nwaPXurNxzJAzny8eY&amp;h=AT09HrXBXCKZBFP2w_QNB_x3e2DYcueVwIDyKDQN9b1VGCzCX1RtOemkjmk1gKHuW4p71BZnNNMjsdebmLEW5vFklr3b1fJWVIuESoAfwP8Wq2V_2WF_gI_Hv2J4yQWXnnNFFDEk\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Youtube<\/strong><\/a><strong>.<\/strong><\/p>\n\n\n\n<p><strong>ACERCA DE HANWHA TECHWIN<\/strong><\/p>\n\n\n\n<p>Hanwha Techwin ofrece soluciones de videovigilancia confiables para satisfacer las necesidades actuales y futuras de los profesionales de la seguridad. La experiencia acumulada durante m\u00e1s de 30 a\u00f1os en tecnolog\u00edas \u00f3pticas y de procesamiento de im\u00e1genes nos ha permitido afianzar una posici\u00f3n de liderazgo en el campo de las soluciones de seguridad, desarrollando y fabricando sistemas de seguridad vanguardistas en Corea. Con Wisenet, nuestra marca l\u00edder, Hanwha Techwin seguir\u00e1 fortaleciendo sus inversiones en desarrollo y comercializaci\u00f3n en el negocio de la seguridad para garantizar el crecimiento futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wisenet 7, fabricado directamente por la compa\u00f1\u00eda en Corea, cuenta con Inteligencia Artificial, ideal para capturar los diferentes atributos de cualquier objeto, incluyendo personas, veh\u00edculos, caras y matr\u00edculas. Hanwha Techwin, un l\u00edder global en soluciones de videovigilancia, ha anunciado el lanzamiento del nuevo chipset Wisenet 7, la m\u00e1s reciente adici\u00f3n a la familia de procesadores [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_joinchat":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[66,7],"tags":[439],"class_list":["post-10147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-videovigilancia","tag-hanwha-techwin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hanwha Techwin: nuevo nivel con chipset Wisenet 7 - InfoSeguridadIT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hanwha Techwin: nuevo nivel con chipset Wisenet 7 - InfoSeguridadIT\" \/>\n<meta property=\"og:description\" content=\"Wisenet 7, fabricado directamente por la compa\u00f1\u00eda en Corea, cuenta con Inteligencia Artificial, ideal para capturar los diferentes atributos de cualquier objeto, incluyendo personas, veh\u00edculos, caras y matr\u00edculas. Hanwha Techwin, un l\u00edder global en soluciones de videovigilancia, ha anunciado el lanzamiento del nuevo chipset Wisenet 7, la m\u00e1s reciente adici\u00f3n a la familia de procesadores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/\" \/>\n<meta property=\"og:site_name\" content=\"InfoSeguridadIT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-03T03:51:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-01T03:55:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/hanwa-infogremio.jpg?fit=598%2C361&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"598\" \/>\n\t<meta property=\"og:image:height\" content=\"361\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InfoSeguridadIT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:site\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"InfoSeguridadIT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/\"},\"author\":{\"name\":\"InfoSeguridadIT\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\"},\"headline\":\"Hanwha Techwin: nuevo nivel con chipset Wisenet 7\",\"datePublished\":\"2020-06-03T03:51:00+00:00\",\"dateModified\":\"2020-07-01T03:55:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/\"},\"wordCount\":769,\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/hanwa-infogremio.jpg\",\"keywords\":[\"Hanwha Techwin\"],\"articleSection\":[\"Actualidad\",\"Videovigilancia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/\",\"name\":\"Hanwha Techwin: nuevo nivel con chipset Wisenet 7 - InfoSeguridadIT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/hanwa-infogremio.jpg\",\"datePublished\":\"2020-06-03T03:51:00+00:00\",\"dateModified\":\"2020-07-01T03:55:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/hanwa-infogremio.jpg\",\"contentUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/hanwa-infogremio.jpg\",\"width\":598,\"height\":361,\"caption\":\"hanwa infogremio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2020\\\/06\\\/03\\\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hanwha Techwin: nuevo nivel con chipset Wisenet 7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"name\":\"InfoSeguridadIT\",\"description\":\"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.\",\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\",\"name\":\"InfoSeguridadIT\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"contentUrl\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"width\":400,\"height\":111,\"caption\":\"InfoSeguridadIT\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\",\"https:\\\/\\\/x.com\\\/gremioseguridad\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ramiro-de-rosa--7879a99\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\",\"name\":\"InfoSeguridadIT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"caption\":\"InfoSeguridadIT\"},\"sameAs\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\\\/\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\"],\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/author\\\/ramiroderosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hanwha Techwin: nuevo nivel con chipset Wisenet 7 - InfoSeguridadIT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/","og_locale":"es_ES","og_type":"article","og_title":"Hanwha Techwin: nuevo nivel con chipset Wisenet 7 - InfoSeguridadIT","og_description":"Wisenet 7, fabricado directamente por la compa\u00f1\u00eda en Corea, cuenta con Inteligencia Artificial, ideal para capturar los diferentes atributos de cualquier objeto, incluyendo personas, veh\u00edculos, caras y matr\u00edculas. Hanwha Techwin, un l\u00edder global en soluciones de videovigilancia, ha anunciado el lanzamiento del nuevo chipset Wisenet 7, la m\u00e1s reciente adici\u00f3n a la familia de procesadores [&hellip;]","og_url":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/","og_site_name":"InfoSeguridadIT","article_publisher":"https:\/\/www.facebook.com\/Infoseguridadit","article_author":"https:\/\/www.facebook.com\/Infoseguridadit\/","article_published_time":"2020-06-03T03:51:00+00:00","article_modified_time":"2020-07-01T03:55:18+00:00","og_image":[{"width":598,"height":361,"url":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/hanwa-infogremio.jpg?fit=598%2C361&ssl=1","type":"image\/jpeg"}],"author":"InfoSeguridadIT","twitter_card":"summary_large_image","twitter_creator":"@gremioseguridad","twitter_site":"@gremioseguridad","twitter_misc":{"Escrito por":"InfoSeguridadIT","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/#article","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/"},"author":{"name":"InfoSeguridadIT","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80"},"headline":"Hanwha Techwin: nuevo nivel con chipset Wisenet 7","datePublished":"2020-06-03T03:51:00+00:00","dateModified":"2020-07-01T03:55:18+00:00","mainEntityOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/"},"wordCount":769,"publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/hanwa-infogremio.jpg","keywords":["Hanwha Techwin"],"articleSection":["Actualidad","Videovigilancia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/","url":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/","name":"Hanwha Techwin: nuevo nivel con chipset Wisenet 7 - InfoSeguridadIT","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/#primaryimage"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/hanwa-infogremio.jpg","datePublished":"2020-06-03T03:51:00+00:00","dateModified":"2020-07-01T03:55:18+00:00","breadcrumb":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/#primaryimage","url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/hanwa-infogremio.jpg","contentUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/hanwa-infogremio.jpg","width":598,"height":361,"caption":"hanwa infogremio"},{"@type":"BreadcrumbList","@id":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/03\/hanwha-techwin-nuevo-nivel-con-chipset-wisenet-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoseguridadit.com\/electronica\/"},{"@type":"ListItem","position":2,"name":"Hanwha Techwin: nuevo nivel con chipset Wisenet 7"}]},{"@type":"WebSite","@id":"https:\/\/infoseguridadit.com\/electronica\/#website","url":"https:\/\/infoseguridadit.com\/electronica\/","name":"InfoSeguridadIT","description":"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.","publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoseguridadit.com\/electronica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoseguridadit.com\/electronica\/#organization","name":"InfoSeguridadIT","url":"https:\/\/infoseguridadit.com\/electronica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/","url":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","contentUrl":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","width":400,"height":111,"caption":"InfoSeguridadIT"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Infoseguridadit","https:\/\/x.com\/gremioseguridad","https:\/\/www.instagram.com\/infoseguridadit\/","https:\/\/www.linkedin.com\/in\/ramiro-de-rosa--7879a99\/"]},{"@type":"Person","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80","name":"InfoSeguridadIT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","caption":"InfoSeguridadIT"},"sameAs":["https:\/\/infoseguridadit.com\/electronica\/","https:\/\/www.facebook.com\/Infoseguridadit\/","https:\/\/www.instagram.com\/infoseguridadit"],"url":"https:\/\/infoseguridadit.com\/electronica\/author\/ramiroderosa\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/hanwa-infogremio.jpg","jetpack-related-posts":[{"id":11088,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/11\/02\/hanwha-2\/","url_meta":{"origin":10147,"position":0},"title":"Hanwha Techwin se mueve en innovaci\u00f3n desde hace 30 a\u00f1os por la seguridad de sus usuarios.","author":"InfoSeguridadIT","date":"2 de noviembre de 2020","format":false,"excerpt":"Hanwha ha invertido durante tres d\u00e9cadas en su l\u00ednea de productos Wisenet para mantenerse a la vanguardia de la industria de videovigilancia. Hanwha Techwin, un l\u00edder global en soluciones de videovigilancia, no deja de moverse en innovaci\u00f3n con excelencia desde 1990 a trav\u00e9s de una l\u00ednea completa de productos de\u2026","rel":"","context":"En \u00abVideovigilancia\u00bb","block_context":{"text":"Videovigilancia","link":"https:\/\/infoseguridadit.com\/electronica\/category\/videovigilancia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/10\/Fwd-Hanwha-Techwin-se-mueve-en-innovacion-desde-hace-30-anos-por-la-seguridad-de-sus-usuarios-infoseguridadIt-foto-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10670,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/08\/26\/wisenet-2\/","url_meta":{"origin":10147,"position":1},"title":"Wisenet, hacia una nueva era de Videovigilancia Inteligente","author":"InfoSeguridadIT","date":"26 de agosto de 2020","format":false,"excerpt":"Wisenet Serie P logran, entre otras, detectar y clasificar tanto personas como veh\u00edculos en tiempo real, gracias a un potente motor de inteligencia artificial. A medida que la inteligencia artificial (IA) se adopte m\u00e1s ampliamente en todas las industrias, es probable que se incorpore a\u00fan m\u00e1s en la videovigilancia durante\u2026","rel":"","context":"En \u00abInformes\u00bb","block_context":{"text":"Informes","link":"https:\/\/infoseguridadit.com\/electronica\/category\/inf\/"},"img":{"alt_text":"wisenet infogremio","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/08\/wisenet-infogremio.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/08\/wisenet-infogremio.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/08\/wisenet-infogremio.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/08\/wisenet-infogremio.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/08\/wisenet-infogremio.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9860,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/04\/20\/hanwha-techwin-3\/","url_meta":{"origin":10147,"position":2},"title":"Hanwha Techwin presenta las c\u00e1maras AI Wisenet P","author":"InfoSeguridadIT","date":"20 de abril de 2020","format":false,"excerpt":"Hanwha Techwin anunci\u00f3 el lanzamiento de sus\u00a0c\u00e1maras\u00a0AI de la\u00a0serie Wisenet P. Se pueden combinar con Wisenet SSM y Wisenet Retail Insight v2.0, para completar el paquete de\u00a0seguridad\u00a0perfecto que d\u00e9 comienzo a una nueva era de videovigilancia inteligente. \u00a0 Equipada con un potente motor de\u00a0inteligencia artificial\u00a0(IA), esta c\u00e1maras logra detectar y\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/04\/Hanwha-Techwin.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/04\/Hanwha-Techwin.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/04\/Hanwha-Techwin.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/04\/Hanwha-Techwin.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/04\/Hanwha-Techwin.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":10478,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/07\/29\/hanwha-techwin-4\/","url_meta":{"origin":10147,"position":3},"title":"Hanwha Techwin fortalece sus pol\u00edticas de ciberseguridad y la protecci\u00f3n de datos","author":"InfoSeguridadIT","date":"29 de julio de 2020","format":false,"excerpt":"Hanwha Techwin, un l\u00edder global en soluciones de videovigilancia, ha seguido renovando sus compromisos con la ciberseguridad y la protecci\u00f3n de datos en sus productos. La compa\u00f1\u00eda surcoreana entiende la importancia de la seguridad cibern\u00e9tica, por lo cual ha incorporado en su nuevo chipset, Wisenet7, protocolos mejorados de protecci\u00f3n, encriptaci\u00f3n\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"hanwha infogremio","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/hanwha-infogremio.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/hanwha-infogremio.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/hanwha-infogremio.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/hanwha-infogremio.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10150,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/25\/videovigilancia-al-servicio-del-big-data-y-el-iot\/","url_meta":{"origin":10147,"position":4},"title":"Videovigilancia al servicio del Big Data y el IoT","author":"InfoSeguridadIT","date":"25 de junio de 2020","format":false,"excerpt":"En 2017, Bogot\u00e1 alcanz\u00f3 una de las tasas de homicidios m\u00e1s bajas de las \u00faltimas tres d\u00e9cadas. Este registro hist\u00f3rico coincidi\u00f3 con el fortalecimiento del sistema de videovigilancia de la capital colombiana al pasar de 267 c\u00e1maras que funcionaban en 2015 a 1.612 ese a\u00f1o conectadas al Centro de Comando,\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/Jhayr-Go%CC%81mez-director-de-Ventas-en-la-Regio%CC%81n-Andina-de-Hanwha-Techwin-1.gif?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/Jhayr-Go%CC%81mez-director-de-Ventas-en-la-Regio%CC%81n-Andina-de-Hanwha-Techwin-1.gif?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/Jhayr-Go%CC%81mez-director-de-Ventas-en-la-Regio%CC%81n-Andina-de-Hanwha-Techwin-1.gif?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":10205,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/07\/07\/transformacion-del-sistema-de-videovigilancia-del-sector-bancario-en-nicaragua-con-hanwha-techwin\/","url_meta":{"origin":10147,"position":5},"title":"Transformaci\u00f3n del sistema de videovigilancia bancaria en Nicaragua con Hanwha Techwin","author":"InfoSeguridadIT","date":"7 de julio de 2020","format":false,"excerpt":"En este proceso, los bancos no solo cambiaron de marca, sino que tambi\u00e9n migraron a tecnolog\u00eda IP. La capacidad de los sistemas de videovigilancia basados en redes IP ha transformado la forma en que la direcci\u00f3n de seguridad de los bancos garantiza la protecci\u00f3n de bienes y personas. El centro\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"hanwha infogremio","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/unnamed.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/unnamed.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/unnamed.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/unnamed.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/unnamed.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/07\/unnamed.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/p6cGtH-2DF","_links":{"self":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/10147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/comments?post=10147"}],"version-history":[{"count":1,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/10147\/revisions"}],"predecessor-version":[{"id":10149,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/10147\/revisions\/10149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media\/10148"}],"wp:attachment":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media?parent=10147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/categories?post=10147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/tags?post=10147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}