{"id":11841,"date":"2021-06-04T12:42:30","date_gmt":"2021-06-04T15:42:30","guid":{"rendered":"http:\/\/gremioseguridad.com\/electronica\/?p=11841"},"modified":"2021-06-04T12:42:52","modified_gmt":"2021-06-04T15:42:52","slug":"la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc","status":"publish","type":"post","link":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/","title":{"rendered":"La serie UNV Heat-Tracker asegura el lugar de trabajo"},"content":{"rendered":"\n<p>BHP est\u00e1 ubicado en Av. Cerro El Plomo N\u00ba 6000, junto a Av. Manquehue Norte, comuna de Las Condes, Chile. El \u00e1rea total de este edificio es de 26,370 m2 con 18 pisos, 7 niveles subterr\u00e1neos y 847 estacionamientos. Los terminales de medici\u00f3n de temperatura UNV est\u00e1n instalados en las entradas y estacionamientos, los cuales est\u00e1n integrados con el sistema de control de acceso PACOM.<\/p>\n\n\n\n<p>Los desaf\u00edos<\/p>\n\n\n\n<p>Con la soluci\u00f3n de control de acceso tradicional, se requiere medir la temperatura y detectar el uso de una m\u00e1scara manualmente durante el per\u00edodo del coronavirus, lo que desperdiciar\u00eda mano de obra adicional y costar\u00eda mucho tiempo y posiblemente aumentar\u00eda el riesgo de infecci\u00f3n cruzada. Adem\u00e1s, la p\u00e9rdida de la tarjeta de acceso o entrada m\u00faltiple a trav\u00e9s de una tarjeta ocurre con bastante frecuencia lo que genera un riesgo de seguridad.<\/p>\n\n\n\n<p>La soluci\u00f3n de UNV<\/p>\n\n\n\n<p><a href=\"https:\/\/global.uniview.com\/Products\/Heat-Tracker\/OET-213H-BTS1-BD\/\">OET-213H-BTS1-BD<\/a>, con m\u00f3dulo de detecci\u00f3n de temperatura de mu\u00f1eca sin contacto, rango de medici\u00f3n de 30\u00baC a 45\u00baC, precisi\u00f3n de 0.1 y la desviaci\u00f3n es menor o igual a 0.3\u00baC, puede evitar el contacto f\u00edsico durante la epidemia y reducir la posibilidad de infecci\u00f3n cruzada.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"362\" src=\"http:\/\/gremioseguridad.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview.jpg\" alt=\"\" class=\"wp-image-11842\" srcset=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview.jpg 480w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview-300x226.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure><\/div>\n\n\n\n<p>Al mismo tiempo, incluye un sistema de asistencia, que puede administrar a los empleados de manera m\u00e1s eficiente mientras mide la temperatura corporal. Los datos de acceso y de asistencia se pueden clasificar y administrar a trav\u00e9s del software de administraci\u00f3n EZStation o EZAccess, que es conveniente para que el administrador los gestione.<\/p>\n\n\n\n<p>Este sistema cuenta con un chip con Deep learning incorporado, OET-213H-BTS1-BD admite el reconocimiento facial incluso con la m\u00e1scara puesta. Su capacidad llega a 10,000 caras y la lista blanca ayuda a administrar mejor la informaci\u00f3n de muchas personas. Estas caracter\u00edsticas del producto pueden proteger eficazmente la informaci\u00f3n y la seguridad de los empleados en el edificio.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"476\" height=\"358\" src=\"http:\/\/gremioseguridad.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview-b.jpg\" alt=\"\" class=\"wp-image-11843\" srcset=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview-b.jpg 476w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview-b-300x226.jpg 300w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>BHP est\u00e1 ubicado en Av. Cerro El Plomo N\u00ba 6000, junto a Av. Manquehue Norte, comuna de Las Condes, Chile. El \u00e1rea total de este edificio es de 26,370 m2 con 18 pisos, 7 niveles subterr\u00e1neos y 847 estacionamientos. Los terminales de medici\u00f3n de temperatura UNV est\u00e1n instalados en las entradas y estacionamientos, los cuales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11844,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_joinchat":{"view":"no"},"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[66,7],"tags":[507],"class_list":["post-11841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-videovigilancia","tag-uniview"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La serie UNV Heat-Tracker asegura el lugar de trabajo - InfoSeguridadIT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La serie UNV Heat-Tracker asegura el lugar de trabajo - InfoSeguridadIT\" \/>\n<meta property=\"og:description\" content=\"BHP est\u00e1 ubicado en Av. Cerro El Plomo N\u00ba 6000, junto a Av. Manquehue Norte, comuna de Las Condes, Chile. El \u00e1rea total de este edificio es de 26,370 m2 con 18 pisos, 7 niveles subterr\u00e1neos y 847 estacionamientos. Los terminales de medici\u00f3n de temperatura UNV est\u00e1n instalados en las entradas y estacionamientos, los cuales [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/\" \/>\n<meta property=\"og:site_name\" content=\"InfoSeguridadIT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-04T15:42:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-04T15:42:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview-chile.jpg?fit=988%2C556&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"988\" \/>\n\t<meta property=\"og:image:height\" content=\"556\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InfoSeguridadIT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:site\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"InfoSeguridadIT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/\"},\"author\":{\"name\":\"InfoSeguridadIT\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\"},\"headline\":\"La serie UNV Heat-Tracker asegura el lugar de trabajo\",\"datePublished\":\"2021-06-04T15:42:30+00:00\",\"dateModified\":\"2021-06-04T15:42:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/\"},\"wordCount\":336,\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/uniview-chile.jpg\",\"keywords\":[\"uniview\"],\"articleSection\":[\"Actualidad\",\"Videovigilancia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/\",\"name\":\"La serie UNV Heat-Tracker asegura el lugar de trabajo - InfoSeguridadIT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/uniview-chile.jpg\",\"datePublished\":\"2021-06-04T15:42:30+00:00\",\"dateModified\":\"2021-06-04T15:42:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/uniview-chile.jpg\",\"contentUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/uniview-chile.jpg\",\"width\":988,\"height\":556},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2021\\\/06\\\/04\\\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La serie UNV Heat-Tracker asegura el lugar de trabajo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"name\":\"InfoSeguridadIT\",\"description\":\"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.\",\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\",\"name\":\"InfoSeguridadIT\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"contentUrl\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"width\":400,\"height\":111,\"caption\":\"InfoSeguridadIT\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\",\"https:\\\/\\\/x.com\\\/gremioseguridad\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ramiro-de-rosa--7879a99\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\",\"name\":\"InfoSeguridadIT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"caption\":\"InfoSeguridadIT\"},\"sameAs\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\\\/\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\"],\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/author\\\/ramiroderosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La serie UNV Heat-Tracker asegura el lugar de trabajo - InfoSeguridadIT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/","og_locale":"es_ES","og_type":"article","og_title":"La serie UNV Heat-Tracker asegura el lugar de trabajo - InfoSeguridadIT","og_description":"BHP est\u00e1 ubicado en Av. Cerro El Plomo N\u00ba 6000, junto a Av. Manquehue Norte, comuna de Las Condes, Chile. El \u00e1rea total de este edificio es de 26,370 m2 con 18 pisos, 7 niveles subterr\u00e1neos y 847 estacionamientos. Los terminales de medici\u00f3n de temperatura UNV est\u00e1n instalados en las entradas y estacionamientos, los cuales [&hellip;]","og_url":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/","og_site_name":"InfoSeguridadIT","article_publisher":"https:\/\/www.facebook.com\/Infoseguridadit","article_author":"https:\/\/www.facebook.com\/Infoseguridadit\/","article_published_time":"2021-06-04T15:42:30+00:00","article_modified_time":"2021-06-04T15:42:52+00:00","og_image":[{"width":988,"height":556,"url":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview-chile.jpg?fit=988%2C556&ssl=1","type":"image\/jpeg"}],"author":"InfoSeguridadIT","twitter_card":"summary_large_image","twitter_creator":"@gremioseguridad","twitter_site":"@gremioseguridad","twitter_misc":{"Escrito por":"InfoSeguridadIT","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/#article","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/"},"author":{"name":"InfoSeguridadIT","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80"},"headline":"La serie UNV Heat-Tracker asegura el lugar de trabajo","datePublished":"2021-06-04T15:42:30+00:00","dateModified":"2021-06-04T15:42:52+00:00","mainEntityOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/"},"wordCount":336,"publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview-chile.jpg","keywords":["uniview"],"articleSection":["Actualidad","Videovigilancia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/","url":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/","name":"La serie UNV Heat-Tracker asegura el lugar de trabajo - InfoSeguridadIT","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/#primaryimage"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview-chile.jpg","datePublished":"2021-06-04T15:42:30+00:00","dateModified":"2021-06-04T15:42:52+00:00","breadcrumb":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/#primaryimage","url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview-chile.jpg","contentUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview-chile.jpg","width":988,"height":556},{"@type":"BreadcrumbList","@id":"https:\/\/infoseguridadit.com\/electronica\/2021\/06\/04\/la-serie-unv-heat-tracker-asegura-el-lugar-de-trabajo-de-bhp-chile-inc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoseguridadit.com\/electronica\/"},{"@type":"ListItem","position":2,"name":"La serie UNV Heat-Tracker asegura el lugar de trabajo"}]},{"@type":"WebSite","@id":"https:\/\/infoseguridadit.com\/electronica\/#website","url":"https:\/\/infoseguridadit.com\/electronica\/","name":"InfoSeguridadIT","description":"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.","publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoseguridadit.com\/electronica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoseguridadit.com\/electronica\/#organization","name":"InfoSeguridadIT","url":"https:\/\/infoseguridadit.com\/electronica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/","url":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","contentUrl":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","width":400,"height":111,"caption":"InfoSeguridadIT"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Infoseguridadit","https:\/\/x.com\/gremioseguridad","https:\/\/www.instagram.com\/infoseguridadit\/","https:\/\/www.linkedin.com\/in\/ramiro-de-rosa--7879a99\/"]},{"@type":"Person","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80","name":"InfoSeguridadIT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","caption":"InfoSeguridadIT"},"sameAs":["https:\/\/infoseguridadit.com\/electronica\/","https:\/\/www.facebook.com\/Infoseguridadit\/","https:\/\/www.instagram.com\/infoseguridadit"],"url":"https:\/\/infoseguridadit.com\/electronica\/author\/ramiroderosa\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/06\/uniview-chile.jpg","jetpack-related-posts":[{"id":11431,"url":"https:\/\/infoseguridadit.com\/electronica\/2021\/02\/12\/equipo-de-camara-unv-wifi-desplegado-en-la-selva-oriental-de-ecuador\/","url_meta":{"origin":11841,"position":0},"title":"Equipo de c\u00e1mara UNV WIFI desplegado en la selva oriental de Ecuador","author":"InfoSeguridadIT","date":"12 de febrero de 2021","format":false,"excerpt":"La construcci\u00f3n de CCTV en \u00e1reas monta\u00f1osas siempre se enfrenta a malos entornos de construcci\u00f3n, como el suministro de energ\u00eda y la red. La densa vegetaci\u00f3n de las zonas monta\u00f1osas est\u00e1 severamente bloqueada. El proyecto en la selva oriental de Ecuador consta de dos contenedores de reacondicionamiento que se utilizan\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"uniview","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/02\/1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/02\/1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/02\/1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/02\/1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/02\/1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15617,"url":"https:\/\/infoseguridadit.com\/electronica\/2024\/12\/17\/hid-bambu\/","url_meta":{"origin":11841,"position":1},"title":"HID y Credenciales m\u00f3viles de bamb\u00fa: el camino hacia una identificaci\u00f3n sostenible","author":"InfoSeguridadIT","date":"17 de diciembre de 2024","format":false,"excerpt":"La transformaci\u00f3n digital y los esfuerzos hacia la sostenibilidad han encontrado un punto de convergencia en Am\u00e9rica Latina, una regi\u00f3n donde la adopci\u00f3n de tecnolog\u00edas m\u00f3viles est\u00e1 marcando la pauta.\u00a0 La adopci\u00f3n masiva de tel\u00e9fonos inteligentes ha transformado fundamentalmente la forma en que se interact\u00faa con el mundo. Para la\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/12\/pacs-eco-card-signo-40-reader-female-hand.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/12\/pacs-eco-card-signo-40-reader-female-hand.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/12\/pacs-eco-card-signo-40-reader-female-hand.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/12\/pacs-eco-card-signo-40-reader-female-hand.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10005,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/06\/10\/caracteristicas-extraordinarias-la-serie-unv-prime-ii\/","url_meta":{"origin":11841,"position":2},"title":"Caracter\u00edsticas extraordinarias de la serie UNV PRIME II","author":"InfoSeguridadIT","date":"10 de junio de 2020","format":false,"excerpt":"Uniview, uno de los principales fabricantes mundiales de productos y soluciones de videovigilancia, presenta su c\u00e1mara de la serie PRIME II. La mejor caracter\u00edstica de los nuevos productos es el soporte de la tecnolog\u00eda LightHunter. Con la combinaci\u00f3n de la tecnolog\u00eda LightHunter y la resoluci\u00f3n de 4MP, todos estos productos\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"http:\/\/www.uniview.com\/Products\/Cameras\/Prime\/II\/8\/","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/06\/prime-II.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/06\/prime-II.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/06\/prime-II.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/06\/prime-II.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/06\/prime-II.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/06\/prime-II.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":12541,"url":"https:\/\/infoseguridadit.com\/electronica\/2022\/01\/15\/uniview-mexico\/","url_meta":{"origin":11841,"position":3},"title":"UNIVIEW brinda una mayor protecci\u00f3n al transporte en Cable en M\u00e9xico.","author":"InfoSeguridadIT","date":"15 de enero de 2022","format":false,"excerpt":"Uniview implement\u00f3 un sistema completo y minucioso para proteger mejor el lugar. El \u00e1rea de entrada y el lobby de espera tienen un \u00e1rea amplia. La funci\u00f3n de correcci\u00f3n de la c\u00e1mara de ojo de pez se puede utilizar para ver claramente todos los lugares. La temperatura del telef\u00e9rico es\u2026","rel":"","context":"En \u00abInformes\u00bb","block_context":{"text":"Informes","link":"https:\/\/infoseguridadit.com\/electronica\/category\/inf\/"},"img":{"alt_text":"uniview","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/12\/20211209_1817362_image002_920327_169683_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/12\/20211209_1817362_image002_920327_169683_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2021\/12\/20211209_1817362_image002_920327_169683_0.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":12608,"url":"https:\/\/infoseguridadit.com\/electronica\/2022\/02\/24\/12608\/","url_meta":{"origin":11841,"position":4},"title":"Uniview lanza nuevas c\u00e1maras de red ColorHunter","author":"InfoSeguridadIT","date":"24 de febrero de 2022","format":false,"excerpt":"El color y los detalles siempre se pierden por la noche, lo cual es un problema com\u00fan en las c\u00e1maras tradicionales. En respuesta a estos problemas, Uniview, pionero y l\u00edder de la videovigilancia IP, ha lanzado su serie ColorHunter. Basado en la c\u00e1mara ColorHunter de 5MP, Uniview ha lanzado una\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/03\/colorhunter-3.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14076,"url":"https:\/\/infoseguridadit.com\/electronica\/2023\/05\/23\/hikvision-9\/","url_meta":{"origin":11841,"position":5},"title":"Hikvision: Seguridad orientada a generar mejores ventas","author":"InfoSeguridadIT","date":"23 de mayo de 2023","format":false,"excerpt":"Hikvision present\u00f3 una soluci\u00f3n seguridad inteligente para\u00a0retail\u00a0y centros comerciales en la Argentina que -no solo brindan una protecci\u00f3n completa- sino que tambi\u00e9n mejoran la experiencia del cliente y optimizan la gesti\u00f3n del negocio. Uno de los principales diferenciales que presenta la compa\u00f1\u00eda es que estas soluciones son escalables y est\u00e1n\u2026","rel":"","context":"En \u00abInformes\u00bb","block_context":{"text":"Informes","link":"https:\/\/infoseguridadit.com\/electronica\/category\/inf\/"},"img":{"alt_text":"hikvision","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/hikvision.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/hikvision.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/hikvision.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/hikvision.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/hikvision.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/hikvision.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/p6cGtH-34Z","_links":{"self":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/11841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/comments?post=11841"}],"version-history":[{"count":2,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/11841\/revisions"}],"predecessor-version":[{"id":11846,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/11841\/revisions\/11846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media\/11844"}],"wp:attachment":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media?parent=11841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/categories?post=11841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/tags?post=11841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}