{"id":13140,"date":"2022-08-01T19:51:00","date_gmt":"2022-08-01T22:51:00","guid":{"rendered":"http:\/\/infoseguridadit.com\/electronica\/?p=13140"},"modified":"2022-08-23T06:23:58","modified_gmt":"2022-08-23T09:23:58","slug":"marshall","status":"publish","type":"post","link":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/","title":{"rendered":"MARSHALL inaugura nuevas oficinas comerciales"},"content":{"rendered":"\n<p>MARSHALL no para de crecer. Luego de sorprender en 2021 con el lanzamiento del primer panel de alarma 4G + WIFI fabricado en el pa\u00eds, hoy inaugura nuevas oficinas comerciales. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-2-1024x768.jpg\" alt=\"marshall\" class=\"wp-image-13143\" srcset=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-2-1024x768.jpg 1024w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-2-300x225.jpg 300w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-2-768x576.jpg 768w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-2-1536x1152.jpg 1536w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-2-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Hablamos con Alejandro Luna, Socio Gerente de <a rel=\"noreferrer noopener\" href=\"https:\/\/infoseguridadit.com\/electronica\/?s=marshall\" target=\"_blank\">Alarmas<\/a> MARSHALL:<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1l es el objetivo de la apertura de las nuevas oficinas?<\/strong><\/p>\n\n\n\n<p>Con el objetivo de seguir potenciando el crecimiento y desarrollo de la <a rel=\"noreferrer noopener\" href=\"https:\/\/alarmasmarshall.com.ar\/\" target=\"_blank\">empresa<\/a> hemos decidido abrir nuevas oficinas comerciales en el barrio de Villa del Parque. Con un dise\u00f1o totalmente moderno y un amplio espacio de trabajo, podemos brindar una atenci\u00f3n m\u00e1s c\u00f3moda a todos nuestros clientes, con un impactante sal\u00f3n de ventas y una gran sala de capacitaci\u00f3n para seguir generando nuevos instaladores certificados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-oficina-1-768x1024.jpg\" alt=\"\" class=\"wp-image-13151\" srcset=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-oficina-1-768x1024.jpg 768w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-oficina-1-225x300.jpg 225w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-oficina-1-1152x1536.jpg 1152w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-oficina-1-1536x2048.jpg 1536w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/infoseguridadit-marshall-oficina-1-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Tambi\u00e9n dentro de las nuevas oficinas inauguramos el nuevo departamento de suscripciones de chips MARSHALL y la exclusiva mesa de ayuda a distribuidores e instaladores para seguir asistiendo a nuestros clientes en la post venta.<\/p>\n\n\n\n<p>Estamos convencidos que brindamos al mercado productos innovadores y revolucionarios. Hoy lleg\u00f3 el momento de trasladar este crecimiento a la infraestructura de la empresa, brindando una imagen comercial profesional totalmente renovada. Adem\u00e1s al estar a una cuadra de las avenidas San Mart\u00edn y Nazca, se llega r\u00e1pidamente desde cualquier punto de CABA y zona norte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"915\" height=\"1024\" src=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/marshall-oficinas-915x1024.jpg\" alt=\"\" class=\"wp-image-13149\" srcset=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/marshall-oficinas-915x1024.jpg 915w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/marshall-oficinas-268x300.jpg 268w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/marshall-oficinas-768x859.jpg 768w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/marshall-oficinas-1373x1536.jpg 1373w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/marshall-oficinas-1831x2048.jpg 1831w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/marshall-oficinas.jpg 1838w\" sizes=\"auto, (max-width: 915px) 100vw, 915px\" \/><\/figure>\n\n\n\n<p>Por otro lado, las oficinas anteriores siguen operativas exclusivamente para fabricaci\u00f3n y despacho de pedidos para el interior.<\/p>\n\n\n\n<p>MARSHALL OFICINAS COMERCIALES<\/p>\n\n\n\n<p>Direcci\u00f3n: Tinogasta 2748, Villa del Parque, CABA.<br>Tel\u00e9fono: 0810-199-6277<\/p>\n\n\n\n<p>MARSHALL F\u00c1BRICA<\/p>\n\n\n\n<p>Direcci\u00f3n: Granaderos 379, Flores, CABA.<br>Tel\u00e9fono: 4633-3538<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MARSHALL no para de crecer. Luego de sorprender en 2021 con el lanzamiento del primer panel de alarma 4G + WIFI fabricado en el pa\u00eds, hoy inaugura nuevas oficinas comerciales. Hablamos con Alejandro Luna, Socio Gerente de Alarmas MARSHALL: \u00bfCu\u00e1l es el objetivo de la apertura de las nuevas oficinas? Con el objetivo de seguir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_joinchat":{"view":"no"},"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[66],"tags":[520,17,253],"class_list":["post-13140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-header","tag-intrusion","tag-marshall"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MARSHALL inaugura nuevas oficinas comerciales - InfoSeguridadIT<\/title>\n<meta name=\"description\" content=\"Marshall no para de crecer. Luego de sorprender en 2021 con el lanzamiento del primer panel de alarma 4G + WIFI fabricado en el pa\u00eds\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MARSHALL inaugura nuevas oficinas comerciales - InfoSeguridadIT\" \/>\n<meta property=\"og:description\" content=\"Marshall no para de crecer. Luego de sorprender en 2021 con el lanzamiento del primer panel de alarma 4G + WIFI fabricado en el pa\u00eds\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/\" \/>\n<meta property=\"og:site_name\" content=\"InfoSeguridadIT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-01T22:51:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-23T09:23:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/Captura-de-Pantalla-2022-06-01-a-las-15.07.36-1.png?fit=1200%2C371&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"371\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"InfoSeguridadIT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:site\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"InfoSeguridadIT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/\"},\"author\":{\"name\":\"InfoSeguridadIT\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\"},\"headline\":\"MARSHALL inaugura nuevas oficinas comerciales\",\"datePublished\":\"2022-08-01T22:51:00+00:00\",\"dateModified\":\"2022-08-23T09:23:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/\"},\"wordCount\":264,\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Captura-de-Pantalla-2022-06-01-a-las-15.07.36-1.png\",\"keywords\":[\"header\",\"intrusion\",\"marshall\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/\",\"name\":\"MARSHALL inaugura nuevas oficinas comerciales - InfoSeguridadIT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Captura-de-Pantalla-2022-06-01-a-las-15.07.36-1.png\",\"datePublished\":\"2022-08-01T22:51:00+00:00\",\"dateModified\":\"2022-08-23T09:23:58+00:00\",\"description\":\"Marshall no para de crecer. Luego de sorprender en 2021 con el lanzamiento del primer panel de alarma 4G + WIFI fabricado en el pa\u00eds\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Captura-de-Pantalla-2022-06-01-a-las-15.07.36-1.png\",\"contentUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Captura-de-Pantalla-2022-06-01-a-las-15.07.36-1.png\",\"width\":1200,\"height\":371},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2022\\\/08\\\/01\\\/marshall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MARSHALL inaugura nuevas oficinas comerciales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"name\":\"InfoSeguridadIT\",\"description\":\"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.\",\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\",\"name\":\"InfoSeguridadIT\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"contentUrl\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"width\":400,\"height\":111,\"caption\":\"InfoSeguridadIT\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\",\"https:\\\/\\\/x.com\\\/gremioseguridad\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ramiro-de-rosa--7879a99\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\",\"name\":\"InfoSeguridadIT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"caption\":\"InfoSeguridadIT\"},\"sameAs\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\\\/\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\"],\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/author\\\/ramiroderosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MARSHALL inaugura nuevas oficinas comerciales - InfoSeguridadIT","description":"Marshall no para de crecer. Luego de sorprender en 2021 con el lanzamiento del primer panel de alarma 4G + WIFI fabricado en el pa\u00eds","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/","og_locale":"es_ES","og_type":"article","og_title":"MARSHALL inaugura nuevas oficinas comerciales - InfoSeguridadIT","og_description":"Marshall no para de crecer. Luego de sorprender en 2021 con el lanzamiento del primer panel de alarma 4G + WIFI fabricado en el pa\u00eds","og_url":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/","og_site_name":"InfoSeguridadIT","article_publisher":"https:\/\/www.facebook.com\/Infoseguridadit","article_author":"https:\/\/www.facebook.com\/Infoseguridadit\/","article_published_time":"2022-08-01T22:51:00+00:00","article_modified_time":"2022-08-23T09:23:58+00:00","og_image":[{"width":1200,"height":371,"url":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/Captura-de-Pantalla-2022-06-01-a-las-15.07.36-1.png?fit=1200%2C371&ssl=1","type":"image\/png"}],"author":"InfoSeguridadIT","twitter_card":"summary_large_image","twitter_creator":"@gremioseguridad","twitter_site":"@gremioseguridad","twitter_misc":{"Escrito por":"InfoSeguridadIT","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/#article","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/"},"author":{"name":"InfoSeguridadIT","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80"},"headline":"MARSHALL inaugura nuevas oficinas comerciales","datePublished":"2022-08-01T22:51:00+00:00","dateModified":"2022-08-23T09:23:58+00:00","mainEntityOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/"},"wordCount":264,"publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/Captura-de-Pantalla-2022-06-01-a-las-15.07.36-1.png","keywords":["header","intrusion","marshall"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/","url":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/","name":"MARSHALL inaugura nuevas oficinas comerciales - InfoSeguridadIT","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/#primaryimage"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/Captura-de-Pantalla-2022-06-01-a-las-15.07.36-1.png","datePublished":"2022-08-01T22:51:00+00:00","dateModified":"2022-08-23T09:23:58+00:00","description":"Marshall no para de crecer. Luego de sorprender en 2021 con el lanzamiento del primer panel de alarma 4G + WIFI fabricado en el pa\u00eds","breadcrumb":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/#primaryimage","url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/Captura-de-Pantalla-2022-06-01-a-las-15.07.36-1.png","contentUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/Captura-de-Pantalla-2022-06-01-a-las-15.07.36-1.png","width":1200,"height":371},{"@type":"BreadcrumbList","@id":"https:\/\/infoseguridadit.com\/electronica\/2022\/08\/01\/marshall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoseguridadit.com\/electronica\/"},{"@type":"ListItem","position":2,"name":"MARSHALL inaugura nuevas oficinas comerciales"}]},{"@type":"WebSite","@id":"https:\/\/infoseguridadit.com\/electronica\/#website","url":"https:\/\/infoseguridadit.com\/electronica\/","name":"InfoSeguridadIT","description":"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.","publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoseguridadit.com\/electronica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoseguridadit.com\/electronica\/#organization","name":"InfoSeguridadIT","url":"https:\/\/infoseguridadit.com\/electronica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/","url":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","contentUrl":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","width":400,"height":111,"caption":"InfoSeguridadIT"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Infoseguridadit","https:\/\/x.com\/gremioseguridad","https:\/\/www.instagram.com\/infoseguridadit\/","https:\/\/www.linkedin.com\/in\/ramiro-de-rosa--7879a99\/"]},{"@type":"Person","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80","name":"InfoSeguridadIT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","caption":"InfoSeguridadIT"},"sameAs":["https:\/\/infoseguridadit.com\/electronica\/","https:\/\/www.facebook.com\/Infoseguridadit\/","https:\/\/www.instagram.com\/infoseguridadit"],"url":"https:\/\/infoseguridadit.com\/electronica\/author\/ramiroderosa\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/05\/Captura-de-Pantalla-2022-06-01-a-las-15.07.36-1.png","jetpack-related-posts":[{"id":16523,"url":"https:\/\/infoseguridadit.com\/electronica\/2026\/04\/16\/alarmas-marshall-3\/","url_meta":{"origin":13140,"position":0},"title":"Alarmas Marshall: el rol de Masters Alarmas en el desarrollo del canal y el crecimiento del automonitoreo","author":"InfoSeguridadIT","date":"16 de abril de 2026","format":false,"excerpt":"Alarmas Marshall contin\u00faa consolidando su presencia en el mercado argentino a trav\u00e9s de una red de distribuci\u00f3n s\u00f3lida, donde Masters Alarmas se posiciona como uno de los referentes clave, con m\u00e1s de 15 a\u00f1os de trabajo conjunto con la marca. Seg\u00fan explican desde Masters Alarmas, el v\u00ednculo con Marshall va\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"alarmas marshall","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2026\/04\/alarmas-marshall-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2026\/04\/alarmas-marshall-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2026\/04\/alarmas-marshall-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2026\/04\/alarmas-marshall-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2026\/04\/alarmas-marshall-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2026\/04\/alarmas-marshall-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":14316,"url":"https:\/\/infoseguridadit.com\/electronica\/2023\/07\/10\/marshall-infinit-2\/","url_meta":{"origin":13140,"position":1},"title":"Marshall INFINIT, nuevas funciones en la APP","author":"InfoSeguridadIT","date":"10 de julio de 2023","format":false,"excerpt":"Marshall INFINIT, la empresa contin\u00faa desarrollando nuevas funciones que faciliten el trabajo del instalador y otras que ayudan al usuario a tener una mejor protecci\u00f3n. Veamos a continuaci\u00f3n que trae de nuevo la \u00faltima actualizaci\u00f3n de Marshall Infinit: ARMADO ESPECIAL: Ahora el cliente va a poder activar de forma individual\u2026","rel":"","context":"En \u00abInformes\u00bb","block_context":{"text":"Informes","link":"https:\/\/infoseguridadit.com\/electronica\/category\/inf\/"},"img":{"alt_text":"Marshall infinit infoseguridadit","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/07\/Marshall-infinit.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/07\/Marshall-infinit.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/07\/Marshall-infinit.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":14224,"url":"https:\/\/infoseguridadit.com\/electronica\/2023\/06\/14\/alarmas-marshall-2\/","url_meta":{"origin":13140,"position":2},"title":"Alarmas Marshall, nuevo slogan, nuevo material comercial.","author":"InfoSeguridadIT","date":"14 de junio de 2023","format":false,"excerpt":"Alarmas Marshall, continuando con la estrategia principal de posicionar la marca en la mente del usuario final, mejorando y facilitando todo el proceso comercial del instalador y distribuidor, redefine su slogan. Por qu\u00e9 decidieron cambiar el slogan? No es que ahora Marshall no sea simple, segura y confiable, como lo\u2026","rel":"","context":"En \u00abInformes\u00bb","block_context":{"text":"Informes","link":"https:\/\/infoseguridadit.com\/electronica\/category\/inf\/"},"img":{"alt_text":"alarmas marshall infoseguridadit","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/06\/alarmas-marshall-infoseguridadit.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/06\/alarmas-marshall-infoseguridadit.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/06\/alarmas-marshall-infoseguridadit.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/06\/alarmas-marshall-infoseguridadit.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/06\/alarmas-marshall-infoseguridadit.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/06\/alarmas-marshall-infoseguridadit.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":14183,"url":"https:\/\/infoseguridadit.com\/electronica\/2023\/06\/05\/alarmas-marshall-seg\/","url_meta":{"origin":13140,"position":3},"title":"Alarmas Marshall incorpora a SEG como distribuidor ORO.","author":"InfoSeguridadIT","date":"5 de junio de 2023","format":false,"excerpt":"Alarmas Marshall, uno de los principales fabricantes de alarmas automonitoreadas del pa\u00eds presenta a SEG como distribuidor ORO. Hablamos con Alejandro Luna, Director principal de Alarmas Marshall \u00bfEl foco de SEG es alarmas especificamente?Si bien el enfoque principal de SEG es la venta de su amplia variedad de motores de\u2026","rel":"","context":"En \u00abInformes\u00bb","block_context":{"text":"Informes","link":"https:\/\/infoseguridadit.com\/electronica\/category\/inf\/"},"img":{"alt_text":"alarmas marshall","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/06\/alarmas-marshall.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/06\/alarmas-marshall.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/06\/alarmas-marshall.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/06\/alarmas-marshall.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/06\/alarmas-marshall.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":10692,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/09\/01\/marshall-infinit\/","url_meta":{"origin":13140,"position":4},"title":"MARSHALL INFINIT, lo que se viene en alarmas","author":"InfoSeguridadIT","date":"1 de septiembre de 2020","format":false,"excerpt":"MARSHALL INFINIT parece ser uno de los m\u00e1s novedosos lanzamientos del 2020 en lo que respecta a alarmas. En un a\u00f1o muy at\u00edpico, los fabricantes del novedoso sistema de alarma afirman que ser\u00e1 algo muy diferente a todo lo conocido y se juegan a terminar el a\u00f1o liderando el segmento.\u2026","rel":"","context":"En \u00abIntrusi\u00f3n\u00bb","block_context":{"text":"Intrusi\u00f3n","link":"https:\/\/infoseguridadit.com\/electronica\/category\/intrusion\/"},"img":{"alt_text":"marshall infogremio","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/09\/Captura-de-Pantalla-2020-09-01-a-las-11.16.42.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/09\/Captura-de-Pantalla-2020-09-01-a-las-11.16.42.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/09\/Captura-de-Pantalla-2020-09-01-a-las-11.16.42.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/09\/Captura-de-Pantalla-2020-09-01-a-las-11.16.42.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15547,"url":"https:\/\/infoseguridadit.com\/electronica\/2024\/08\/15\/marshall-4\/","url_meta":{"origin":13140,"position":5},"title":"Marshall: Convertite en Instalador Certificado","author":"InfoSeguridadIT","date":"15 de agosto de 2024","format":false,"excerpt":"Marshall te acerca una certificaci\u00f3n ideal para ganar confianza con los clienetes. En un mercado competitivo, la confianza y la credibilidad son fundamentales. Al certificarte con Marshall, no solo demostrar\u00e1s tu experiencia y conocimiento, sino que tambi\u00e9n ganar\u00e1s la confianza de tus clientes y acceder\u00e1s a beneficios exclusivos que te\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"marshall","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/08\/marshall-infoseguridadit.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/08\/marshall-infoseguridadit.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/08\/marshall-infoseguridadit.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/08\/marshall-infoseguridadit.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/08\/marshall-infoseguridadit.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/s6cGtH-marshall","_links":{"self":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/13140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/comments?post=13140"}],"version-history":[{"count":5,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/13140\/revisions"}],"predecessor-version":[{"id":13153,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/13140\/revisions\/13153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media\/13165"}],"wp:attachment":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media?parent=13140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/categories?post=13140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/tags?post=13140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}