{"id":13976,"date":"2023-02-12T07:53:00","date_gmt":"2023-02-12T10:53:00","guid":{"rendered":"http:\/\/infoseguridadit.com\/electronica\/?p=13976"},"modified":"2023-03-21T13:02:54","modified_gmt":"2023-03-21T16:02:54","slug":"hellgrun-4","status":"publish","type":"post","link":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/","title":{"rendered":"Hellgr\u00fcn present\u00f3 su panel de alarma K\u00fcmmert"},"content":{"rendered":"\n<p>Hellgr\u00fcn present\u00f3 <a href=\"https:\/\/www.hellgrun.com.ar\/kummert-un-panel-de-alarma-creado-especialmente-para-cada-necesidad\/\" target=\"_blank\" rel=\"noreferrer noopener\">K\u00fcmmert<\/a>, un revolucionario panel de alarma. La presentaci\u00f3n se llev\u00f3 a cabo a trav\u00e9s de Zoom junto a la revista <a href=\"https:\/\/infoseguridadit.com\/electronica\/\" target=\"_blank\" rel=\"noreferrer noopener\">InfoSeguridadIT<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"363\" src=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun-1024x363.jpg\" alt=\"hellgrun\" class=\"wp-image-13978\" srcset=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun-1024x363.jpg 1024w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun-300x106.jpg 300w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun-768x272.jpg 768w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun.jpg 1031w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Desde Hellgr\u00fcn estamos muy contentos de haber podido compartir esta experiencia junto a los amigos de InfoseguridadIT. Es un orgullo para nosotros poder presentar el nuevo y revolucionario panel de alarma K\u00fcmmert, contar como fue dise\u00f1ado y producido, y todas sus funciones y prestaciones que llevan la experiencia de usuario a un nuevo nivel.\u201d Paola Koch, l\u00edder de ventas.<\/p>\n\n\n\n<p>Para quienes no pudieron asistir, dejamos debajo la presentaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Presentaci\u00f3n nuevo panel de alarma K\u00fcmmert de Hellgr\u00fcn\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/fQDLGgxwCqI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>Acerca de Hellgr\u00fcn<\/strong><\/p>\n\n\n\n<p>Hellgr\u00fcn es una empresa dedicada a brindar productos electr\u00f3nicos innovadores y de calidad.<\/p>\n\n\n\n<p>Provee productos de seguridad electr\u00f3nica de alta calidad a precios competitivos, con la mejor garant\u00eda y financiaci\u00f3n del mercado.<\/p>\n\n\n\n<p>Estamos abocados al servicio pre y post venta y contamos con un equipo de ingenieros y t\u00e9cnicos comprometidos a brindar la mejor atenci\u00f3n para atender las necesidades y sugerencias de nuestros clientes.<\/p>\n\n\n\n<p><strong>Acerca de K\u00fcmmert<\/strong><\/p>\n\n\n\n<p><strong>K\u00fcmmert<\/strong>&nbsp;es m\u00e1s que un panel de alarma. Es un panel con una concepci\u00f3n de dise\u00f1o y filosof\u00eda de uso totalmente diferente a lo tradicional. Orientado a la prestaci\u00f3n de servicio y a las necesidades de los usuarios, ofrece funciones espec\u00edficas para una experiencia de usuario \u00fanica y para minimizar los costos operativos.<\/p>\n\n\n\n<p>El panel&nbsp;<strong>K\u00fcmmert<\/strong>&nbsp;est\u00e1 acompa\u00f1ado por un software de programaci\u00f3n remota llamado&nbsp;<strong>\u201cHellgr\u00fcn Connect\u201d<\/strong>. Es un software modular de administraci\u00f3n y monitoreo muy completo y f\u00e1cil de usar, especialmente adaptado a las funciones avanzadas del panel. Tanto la administraci\u00f3n como el monitoreo funcionan sobre una misma base de datos otorgando un diferencial de costo operativo muy importante a los prestadores de servicio de monitoreo.<\/p>\n\n\n\n<p>Este software es una herramienta fundamental para facilitar la configuraci\u00f3n de los paneles haci\u00e9ndolo muy sencillo y resguardando la seguridad de datos y claves frente a los instaladores. Permite de esta forma, reducir tanto el tiempo como el costo asociados a la programaci\u00f3n y a la puesta en marcha de los paneles.<\/p>\n\n\n\n<p>M\u00e1s informaci\u00f3n ingresando <a href=\"https:\/\/www.hellgrun.com.ar\/\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hellgr\u00fcn present\u00f3 K\u00fcmmert, un revolucionario panel de alarma. La presentaci\u00f3n se llev\u00f3 a cabo a trav\u00e9s de Zoom junto a la revista InfoSeguridadIT. Desde Hellgr\u00fcn estamos muy contentos de haber podido compartir esta experiencia junto a los amigos de InfoseguridadIT. Es un orgullo para nosotros poder presentar el nuevo y revolucionario panel de alarma K\u00fcmmert, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13978,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_joinchat":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[267],"tags":[520],"class_list":["post-13976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inf","tag-header"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hellgr\u00fcn present\u00f3 su panel de alarma K\u00fcmmert - InfoSeguridadIT<\/title>\n<meta name=\"description\" content=\"Hellgr\u00fcn present\u00f3 K\u00fcmmert, un revolucionario panel de alarma. La presentaci\u00f3n se llev\u00f3 a cabo a trav\u00e9s de Zoom junto a InfoSeguridadIT\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hellgr\u00fcn present\u00f3 su panel de alarma K\u00fcmmert - InfoSeguridadIT\" \/>\n<meta property=\"og:description\" content=\"Hellgr\u00fcn present\u00f3 K\u00fcmmert, un revolucionario panel de alarma. La presentaci\u00f3n se llev\u00f3 a cabo a trav\u00e9s de Zoom junto a InfoSeguridadIT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/\" \/>\n<meta property=\"og:site_name\" content=\"InfoSeguridadIT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-12T10:53:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T16:02:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun.jpg?fit=1031%2C365&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1031\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InfoSeguridadIT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:site\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"InfoSeguridadIT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/\"},\"author\":{\"name\":\"InfoSeguridadIT\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\"},\"headline\":\"Hellgr\u00fcn present\u00f3 su panel de alarma K\u00fcmmert\",\"datePublished\":\"2023-02-12T10:53:00+00:00\",\"dateModified\":\"2023-03-21T16:02:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/\"},\"wordCount\":391,\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/hellgrun.jpg\",\"keywords\":[\"header\"],\"articleSection\":[\"Informes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/\",\"name\":\"Hellgr\u00fcn present\u00f3 su panel de alarma K\u00fcmmert - InfoSeguridadIT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/hellgrun.jpg\",\"datePublished\":\"2023-02-12T10:53:00+00:00\",\"dateModified\":\"2023-03-21T16:02:54+00:00\",\"description\":\"Hellgr\u00fcn present\u00f3 K\u00fcmmert, un revolucionario panel de alarma. La presentaci\u00f3n se llev\u00f3 a cabo a trav\u00e9s de Zoom junto a InfoSeguridadIT\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/hellgrun.jpg\",\"contentUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/hellgrun.jpg\",\"width\":1031,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/02\\\/12\\\/hellgrun-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hellgr\u00fcn present\u00f3 su panel de alarma K\u00fcmmert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"name\":\"InfoSeguridadIT\",\"description\":\"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.\",\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\",\"name\":\"InfoSeguridadIT\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"contentUrl\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"width\":400,\"height\":111,\"caption\":\"InfoSeguridadIT\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\",\"https:\\\/\\\/x.com\\\/gremioseguridad\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ramiro-de-rosa--7879a99\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\",\"name\":\"InfoSeguridadIT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"caption\":\"InfoSeguridadIT\"},\"sameAs\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\\\/\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\"],\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/author\\\/ramiroderosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hellgr\u00fcn present\u00f3 su panel de alarma K\u00fcmmert - InfoSeguridadIT","description":"Hellgr\u00fcn present\u00f3 K\u00fcmmert, un revolucionario panel de alarma. La presentaci\u00f3n se llev\u00f3 a cabo a trav\u00e9s de Zoom junto a InfoSeguridadIT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/","og_locale":"es_ES","og_type":"article","og_title":"Hellgr\u00fcn present\u00f3 su panel de alarma K\u00fcmmert - InfoSeguridadIT","og_description":"Hellgr\u00fcn present\u00f3 K\u00fcmmert, un revolucionario panel de alarma. La presentaci\u00f3n se llev\u00f3 a cabo a trav\u00e9s de Zoom junto a InfoSeguridadIT","og_url":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/","og_site_name":"InfoSeguridadIT","article_publisher":"https:\/\/www.facebook.com\/Infoseguridadit","article_author":"https:\/\/www.facebook.com\/Infoseguridadit\/","article_published_time":"2023-02-12T10:53:00+00:00","article_modified_time":"2023-03-21T16:02:54+00:00","og_image":[{"width":1031,"height":365,"url":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun.jpg?fit=1031%2C365&ssl=1","type":"image\/jpeg"}],"author":"InfoSeguridadIT","twitter_card":"summary_large_image","twitter_creator":"@gremioseguridad","twitter_site":"@gremioseguridad","twitter_misc":{"Escrito por":"InfoSeguridadIT","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/#article","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/"},"author":{"name":"InfoSeguridadIT","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80"},"headline":"Hellgr\u00fcn present\u00f3 su panel de alarma K\u00fcmmert","datePublished":"2023-02-12T10:53:00+00:00","dateModified":"2023-03-21T16:02:54+00:00","mainEntityOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/"},"wordCount":391,"publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun.jpg","keywords":["header"],"articleSection":["Informes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/","url":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/","name":"Hellgr\u00fcn present\u00f3 su panel de alarma K\u00fcmmert - InfoSeguridadIT","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/#primaryimage"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun.jpg","datePublished":"2023-02-12T10:53:00+00:00","dateModified":"2023-03-21T16:02:54+00:00","description":"Hellgr\u00fcn present\u00f3 K\u00fcmmert, un revolucionario panel de alarma. La presentaci\u00f3n se llev\u00f3 a cabo a trav\u00e9s de Zoom junto a InfoSeguridadIT","breadcrumb":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/#primaryimage","url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun.jpg","contentUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun.jpg","width":1031,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/02\/12\/hellgrun-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoseguridadit.com\/electronica\/"},{"@type":"ListItem","position":2,"name":"Hellgr\u00fcn present\u00f3 su panel de alarma K\u00fcmmert"}]},{"@type":"WebSite","@id":"https:\/\/infoseguridadit.com\/electronica\/#website","url":"https:\/\/infoseguridadit.com\/electronica\/","name":"InfoSeguridadIT","description":"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.","publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoseguridadit.com\/electronica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoseguridadit.com\/electronica\/#organization","name":"InfoSeguridadIT","url":"https:\/\/infoseguridadit.com\/electronica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/","url":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","contentUrl":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","width":400,"height":111,"caption":"InfoSeguridadIT"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Infoseguridadit","https:\/\/x.com\/gremioseguridad","https:\/\/www.instagram.com\/infoseguridadit\/","https:\/\/www.linkedin.com\/in\/ramiro-de-rosa--7879a99\/"]},{"@type":"Person","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80","name":"InfoSeguridadIT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","caption":"InfoSeguridadIT"},"sameAs":["https:\/\/infoseguridadit.com\/electronica\/","https:\/\/www.facebook.com\/Infoseguridadit\/","https:\/\/www.instagram.com\/infoseguridadit"],"url":"https:\/\/infoseguridadit.com\/electronica\/author\/ramiroderosa\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/01\/hellgrun.jpg","jetpack-related-posts":[{"id":13733,"url":"https:\/\/infoseguridadit.com\/electronica\/2022\/11\/08\/kummert\/","url_meta":{"origin":13976,"position":0},"title":"K\u00fcmmert, un panel de alarma creado especialmente para cada necesidad","author":"InfoSeguridadIT","date":"8 de noviembre de 2022","format":false,"excerpt":"K\u00fcmmert es m\u00e1s que un panel de alarma. Es un panel con una concepci\u00f3n de dise\u00f1o y filosof\u00eda de uso totalmente diferente a lo tradicional. Orientado a la prestaci\u00f3n de servicio y a las necesidades de los usuarios, ofrece funciones espec\u00edficas para una experiencia de usuario \u00fanica y para minimizar\u2026","rel":"","context":"En \u00abInformes\u00bb","block_context":{"text":"Informes","link":"https:\/\/infoseguridadit.com\/electronica\/category\/inf\/"},"img":{"alt_text":"Ku\u0308mmert","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/11\/Ku%CC%88mmert.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/11\/Ku%CC%88mmert.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/11\/Ku%CC%88mmert.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/11\/Ku%CC%88mmert.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/11\/Ku%CC%88mmert.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14861,"url":"https:\/\/infoseguridadit.com\/electronica\/2023\/12\/20\/hellgrun-e-learning-todo-lo-que-necesitas-para-ser-un-profesional-de-seguridad-e-instalador-kummert-certificado\/","url_meta":{"origin":13976,"position":1},"title":"Hellgr\u00fcn E-Learning, todo lo que necesitas para ser un profesional de seguridad e instalador K\u00fcmmert certificado.","author":"InfoSeguridadIT","date":"20 de diciembre de 2023","format":false,"excerpt":"La revoluci\u00f3n digital ha trascendido todos los aspectos de nuestras vidas, incluyendo la forma en que adquirimos conocimientos. En este contexto, Hellgr\u00fcn E-Learning irrumpe en el escenario de la industria con una propuesta educativa innovadora: convertirte en un experto en seguridad electr\u00f3nica a trav\u00e9s de una plataforma de aprendizaje en\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"hellgr\u00fcn infoseguridadit","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-20-a-las-17.24.20.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-20-a-las-17.24.20.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-20-a-las-17.24.20.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-20-a-las-17.24.20.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-20-a-las-17.24.20.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14996,"url":"https:\/\/infoseguridadit.com\/electronica\/2024\/02\/25\/kummert-k1-4g-la-solucion-definitiva-para-el-problema-de-comunicacion-2g-y-3g\/","url_meta":{"origin":13976,"position":2},"title":"K\u00fcmmert K1 4G, la soluci\u00f3n definitiva para el problema de comunicaci\u00f3n 2G Y 3G","author":"InfoSeguridadIT","date":"25 de febrero de 2024","format":false,"excerpt":"K\u00fcmmert: el panel K\u00fcmmert K1 4G:En un mundo donde la comunicaci\u00f3n y la seguridad son esenciales, presentamos con entusiasmo el nuevo panel de la l\u00ednea . Este nuevo dispositivo no solo aborda de manera innovadora el problema de la obsolescencia del 2G y 3G, sino que tambi\u00e9n se presenta como\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/02\/Captura-de-pantalla-2024-02-25-a-las-21.50.18.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/02\/Captura-de-pantalla-2024-02-25-a-las-21.50.18.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/02\/Captura-de-pantalla-2024-02-25-a-las-21.50.18.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/02\/Captura-de-pantalla-2024-02-25-a-las-21.50.18.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/02\/Captura-de-pantalla-2024-02-25-a-las-21.50.18.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/02\/Captura-de-pantalla-2024-02-25-a-las-21.50.18.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":13690,"url":"https:\/\/infoseguridadit.com\/electronica\/2022\/11\/01\/hellgrun\/","url_meta":{"origin":13976,"position":3},"title":"Hellgr\u00fcn nueva filosof\u00eda y experiencia.","author":"InfoSeguridadIT","date":"1 de noviembre de 2022","format":false,"excerpt":"Hellgr\u00fcn es una marca dedicada a brindar productos innovadores, funcionales y de calidad. Nace de la visi\u00f3n de dos grandes de la industria de seguridad electr\u00f3nica, la combinaci\u00f3n perfecta y complementaria de una empresa de monitoreo y una empresa de importaci\u00f3n y distribuci\u00f3n. Estos grandes de la seguridad se encontraron\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/11\/Portada-Novedad_Co%CC%81mo-nace-Hellgru%CC%88n.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/11\/Portada-Novedad_Co%CC%81mo-nace-Hellgru%CC%88n.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/11\/Portada-Novedad_Co%CC%81mo-nace-Hellgru%CC%88n.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/11\/Portada-Novedad_Co%CC%81mo-nace-Hellgru%CC%88n.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2022\/11\/Portada-Novedad_Co%CC%81mo-nace-Hellgru%CC%88n.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15437,"url":"https:\/\/infoseguridadit.com\/electronica\/2024\/06\/18\/hellgrun-3\/","url_meta":{"origin":13976,"position":4},"title":"Hellgr\u00fcn te invita a convertirte en un experto","author":"InfoSeguridadIT","date":"18 de junio de 2024","format":false,"excerpt":"Hellgr\u00fcn los invita a la capacitaci\u00f3n t\u00e9cnica que se llevar\u00e1 a cabo de manera virtual el pr\u00f3ximo martes 25 de junio a las 15 hs.\u00a0 Podr\u00e1n conocer todo sobre los paneles de alarma K\u00fcmmert, pero adem\u00e1s, durante la capacitaci\u00f3n se har\u00e1 enfoque en c\u00f3mo: Desde nuestro SOFTWARE DE PROGRAMACI\u00d3N INTEGRAL:\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"hellgr\u00fcn","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/06\/Captura-de-pantalla-2024-06-18-a-las-4.53.27%E2%80%AFp.-m.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/06\/Captura-de-pantalla-2024-06-18-a-las-4.53.27%E2%80%AFp.-m.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/06\/Captura-de-pantalla-2024-06-18-a-las-4.53.27%E2%80%AFp.-m.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/06\/Captura-de-pantalla-2024-06-18-a-las-4.53.27%E2%80%AFp.-m.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15367,"url":"https:\/\/infoseguridadit.com\/electronica\/2024\/06\/04\/conectando-expertos-hellgrun-invita-a-instaladores-e-integradores-de-todo-el-pais-a-una-presentacion-exclusiva\/","url_meta":{"origin":13976,"position":5},"title":"Conectando Expertos: Hellgr\u00fcn invita a instaladores e integradores de todo el pa\u00eds a una presentaci\u00f3n exclusiva.\u00a0","author":"InfoSeguridadIT","date":"4 de junio de 2024","format":false,"excerpt":"Helgr\u00fcn invita a descubrir todas las caracter\u00edsticas de sus nuevos paneles para monitoreo y automonitoreo.\u00a0 \"Desde Hellgr\u00fcn, queremos invitarlos a una presentaci\u00f3n dise\u00f1ada especialmente para instaladores e integradores. El evento se llevar\u00e1 a cabo de manera virtual el pr\u00f3ximo 11 de junio a las 14:30hs.\" Fernando Koch, Director Comercial de\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/06\/Camp-Hellgrun-Presentacion-Hellgrun-11-06-24_Banner-infogremio-1-1.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/p6cGtH-3Dq","_links":{"self":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/13976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/comments?post=13976"}],"version-history":[{"count":2,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/13976\/revisions"}],"predecessor-version":[{"id":13980,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/13976\/revisions\/13980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media\/13978"}],"wp:attachment":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media?parent=13976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/categories?post=13976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/tags?post=13976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}