{"id":14561,"date":"2023-10-12T09:14:50","date_gmt":"2023-10-12T12:14:50","guid":{"rendered":"https:\/\/infoseguridadit.com\/electronica\/?p=14561"},"modified":"2023-10-26T11:01:21","modified_gmt":"2023-10-26T14:01:21","slug":"dahua-technology-presenta-dolynk-care-cloud","status":"publish","type":"post","link":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/","title":{"rendered":"Dahua Technology presenta Dolynk Care Cloud"},"content":{"rendered":"\n<p>La nueva plataforma en la nube DoLynk Care ofrece un sistema de servicios fluido basado en la nube que le permite administrar dispositivos en el sitio y disfrutar de una gama completa de servicios. <\/p>\n\n\n\n<p>Gabriel Guette, Gerente de New Business nos cuenta sobre qu\u00e9 trata:<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 es Dolynk Care y qu\u00e9 ofrece?<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua-nota-octubre.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua-nota-octubre.png\" alt=\"\" class=\"wp-image-14562\" width=\"234\" height=\"149\" srcset=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua-nota-octubre.png 994w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua-nota-octubre-300x192.png 300w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua-nota-octubre-768x491.png 768w\" sizes=\"auto, (max-width: 234px) 100vw, 234px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>\u00a0L<em>a nueva plataforma DoLynk Care Cloud ofrece un sistema de servicio confluente basado en la nube que permite administrar dispositivos Dahua in situ y disfrutar de una gama completa de servicios.<\/em><\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 equipos son compatibles con DoLynk Care?<\/strong><\/p>\n\n\n\n<p><em>Actualmente contamos con una amplia gama de productos compatibles con la plataforma incluyendo Alarmas Inal\u00e1mbricas AirShield, los nuevos Switchs cloud, IPC, NVR, XVR y hasta equipos de Video Porter\u00eda y Control de Acceso.<\/em><\/p>\n\n\n\n<p><strong>\u00bfQui\u00e9n puede usar esta aplicaci\u00f3n?<\/strong><\/p>\n\n\n\n<p><em>DoLynk Care est\u00e1 dise\u00f1ado para instaladores e integradores de sistemas.<\/em><\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 ofrece espec\u00edficamente la aplicaci\u00f3n?<\/strong><\/p>\n\n\n\n<p><em>Puede proporcionar un servicio profesional para los usuarios finales a trav\u00e9s de DoLynk Care, configuraci\u00f3n y entrega de dispositivos remotos, notificaci\u00f3n de errores en tiempo real, ticket y recordatorio de errores no resueltos<\/em><\/p>\n\n\n\n<p><em>Es una plataforma profesional y confiable donde se puede administrar los sitios de sus clientes en cualquier momento y en cualquier lugar. Cuando un dispositivo falla, el Instalador recibir\u00e1 una notificaci\u00f3n push de inmediato, lo que permite localizar el problema y resolverlo de forma remota.<\/em><\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 ventajas ofrece este sistema<\/strong>?<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Dolynk-Care-Cloud-.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Dolynk-Care-Cloud-.png\" alt=\"\" class=\"wp-image-14563\" width=\"240\" height=\"161\" srcset=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Dolynk-Care-Cloud-.png 976w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Dolynk-Care-Cloud--300x200.png 300w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Dolynk-Care-Cloud--768x513.png 768w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>\u00a0<em>Nuestra plataforma puede proporcionar a sus clientes un servicio de administraci\u00f3n del estado del dispositivo al administrar sus sitios. Cuando se produce un error, se recibe inmediatamente una notificaci\u00f3n en el portal web y\/o aplicaci\u00f3n DoLynk Care. El sistema tambi\u00e9n cuenta con material y gu\u00edas para solucionar problemas r\u00e1pidamente, adem\u00e1s de sugerir posibles soluciones al problema.<\/em><\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo es la configuraci\u00f3n?<\/strong><\/p>\n\n\n\n<p><em>Con la aplicaci\u00f3n DoLynk Care, se puede realizar la instalaci\u00f3n in situ sin llevar siempre encima la computadora.<\/em><\/p>\n\n\n\n<p><em>El sistema permite iniciar sesi\u00f3n en el Sitio Web del dispositivo para realizar todas las configuraciones de forma remota a trav\u00e9s del portal web de DoLynk Care.<\/em><\/p>\n\n\n\n<p><em>As\u00ed mismo, DoLynk Care permite agregar varios dispositivos al mismo tiempo y gestionarlos por Lotes.<\/em><\/p>\n\n\n\n<p><strong>\u00bfExiste alg\u00fan beneficio extra?<\/strong><\/p>\n\n\n\n<p><em>DoLynk Care permite brindar un servicio personalizado a sus clientes. En la plataforma se pueden asignar distintos operadores de tu compa\u00f1\u00eda a diferentes clientes y as\u00ed poder estar m\u00e1s cerca de ellos. Adem\u00e1s, incluye funciones de evaluaci\u00f3n de rendimiento de cada operador, as\u00ed como un portal para que cada cliente pueda dar una devoluci\u00f3n del servicio brindado.<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><a href=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Dolynk-Care-Cloud-b.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Dolynk-Care-Cloud-b.png\" alt=\"\" class=\"wp-image-14564\" width=\"230\" height=\"161\" srcset=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Dolynk-Care-Cloud-b.png 654w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Dolynk-Care-Cloud-b-300x210.png 300w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p><em>\u00a0De esta forma, con DoLynk Care, tu compa\u00f1\u00eda va a estar a\u00fan m\u00e1s cerca de tus clientes. Cada vez que un cliente abra la app celular DMSS para visualizar su sistema de seguridad va a poder observar el Logo de tu empresa en la pantalla, es decir se puede personalizar la informaci\u00f3n.<\/em><\/p>\n\n\n\n<p>En conclusi\u00f3n, Dahua Technology ofrece una plataforma excelente para expandir el negocio y los ingresos, ahorrar tiempo en los servicios t\u00e9cnicos, mejorar la eficiencia de tu empresa y nunca perder el contacto con tus clientes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nueva plataforma en la nube DoLynk Care ofrece un sistema de servicios fluido basado en la nube que le permite administrar dispositivos en el sitio y disfrutar de una gama completa de servicios. Gabriel Guette, Gerente de New Business nos cuenta sobre qu\u00e9 trata: \u00bfQu\u00e9 es Dolynk Care y qu\u00e9 ofrece? \u00a0La nueva plataforma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14566,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_joinchat":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[267],"tags":[79,515],"class_list":["post-14561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inf","tag-dahua","tag-dahua-technology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dahua Technology presenta Dolynk Care Cloud - InfoSeguridadIT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dahua Technology presenta Dolynk Care Cloud - InfoSeguridadIT\" \/>\n<meta property=\"og:description\" content=\"La nueva plataforma en la nube DoLynk Care ofrece un sistema de servicios fluido basado en la nube que le permite administrar dispositivos en el sitio y disfrutar de una gama completa de servicios. Gabriel Guette, Gerente de New Business nos cuenta sobre qu\u00e9 trata: \u00bfQu\u00e9 es Dolynk Care y qu\u00e9 ofrece? \u00a0La nueva plataforma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/\" \/>\n<meta property=\"og:site_name\" content=\"InfoSeguridadIT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-12T12:14:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-26T14:01:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1834\" \/>\n\t<meta property=\"og:image:height\" content=\"1138\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InfoSeguridadIT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:site\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"InfoSeguridadIT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/\"},\"author\":{\"name\":\"InfoSeguridadIT\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\"},\"headline\":\"Dahua Technology presenta Dolynk Care Cloud\",\"datePublished\":\"2023-10-12T12:14:50+00:00\",\"dateModified\":\"2023-10-26T14:01:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/\"},\"wordCount\":537,\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/dahua.jpg\",\"keywords\":[\"dahua\",\"dahua technology\"],\"articleSection\":[\"Informes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/\",\"name\":\"Dahua Technology presenta Dolynk Care Cloud - InfoSeguridadIT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/dahua.jpg\",\"datePublished\":\"2023-10-12T12:14:50+00:00\",\"dateModified\":\"2023-10-26T14:01:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/dahua.jpg\",\"contentUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/dahua.jpg\",\"width\":1834,\"height\":1138},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/12\\\/dahua-technology-presenta-dolynk-care-cloud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dahua Technology presenta Dolynk Care Cloud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"name\":\"InfoSeguridadIT\",\"description\":\"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.\",\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\",\"name\":\"InfoSeguridadIT\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"contentUrl\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"width\":400,\"height\":111,\"caption\":\"InfoSeguridadIT\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\",\"https:\\\/\\\/x.com\\\/gremioseguridad\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ramiro-de-rosa--7879a99\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\",\"name\":\"InfoSeguridadIT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"caption\":\"InfoSeguridadIT\"},\"sameAs\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\\\/\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\"],\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/author\\\/ramiroderosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dahua Technology presenta Dolynk Care Cloud - InfoSeguridadIT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/","og_locale":"es_ES","og_type":"article","og_title":"Dahua Technology presenta Dolynk Care Cloud - InfoSeguridadIT","og_description":"La nueva plataforma en la nube DoLynk Care ofrece un sistema de servicios fluido basado en la nube que le permite administrar dispositivos en el sitio y disfrutar de una gama completa de servicios. Gabriel Guette, Gerente de New Business nos cuenta sobre qu\u00e9 trata: \u00bfQu\u00e9 es Dolynk Care y qu\u00e9 ofrece? \u00a0La nueva plataforma [&hellip;]","og_url":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/","og_site_name":"InfoSeguridadIT","article_publisher":"https:\/\/www.facebook.com\/Infoseguridadit","article_author":"https:\/\/www.facebook.com\/Infoseguridadit\/","article_published_time":"2023-10-12T12:14:50+00:00","article_modified_time":"2023-10-26T14:01:21+00:00","og_image":[{"width":1834,"height":1138,"url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua.jpg","type":"image\/jpeg"}],"author":"InfoSeguridadIT","twitter_card":"summary_large_image","twitter_creator":"@gremioseguridad","twitter_site":"@gremioseguridad","twitter_misc":{"Escrito por":"InfoSeguridadIT","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/#article","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/"},"author":{"name":"InfoSeguridadIT","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80"},"headline":"Dahua Technology presenta Dolynk Care Cloud","datePublished":"2023-10-12T12:14:50+00:00","dateModified":"2023-10-26T14:01:21+00:00","mainEntityOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/"},"wordCount":537,"publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua.jpg","keywords":["dahua","dahua technology"],"articleSection":["Informes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/","url":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/","name":"Dahua Technology presenta Dolynk Care Cloud - InfoSeguridadIT","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/#primaryimage"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua.jpg","datePublished":"2023-10-12T12:14:50+00:00","dateModified":"2023-10-26T14:01:21+00:00","breadcrumb":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/#primaryimage","url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua.jpg","contentUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua.jpg","width":1834,"height":1138},{"@type":"BreadcrumbList","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/12\/dahua-technology-presenta-dolynk-care-cloud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoseguridadit.com\/electronica\/"},{"@type":"ListItem","position":2,"name":"Dahua Technology presenta Dolynk Care Cloud"}]},{"@type":"WebSite","@id":"https:\/\/infoseguridadit.com\/electronica\/#website","url":"https:\/\/infoseguridadit.com\/electronica\/","name":"InfoSeguridadIT","description":"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.","publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoseguridadit.com\/electronica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoseguridadit.com\/electronica\/#organization","name":"InfoSeguridadIT","url":"https:\/\/infoseguridadit.com\/electronica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/","url":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","contentUrl":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","width":400,"height":111,"caption":"InfoSeguridadIT"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Infoseguridadit","https:\/\/x.com\/gremioseguridad","https:\/\/www.instagram.com\/infoseguridadit\/","https:\/\/www.linkedin.com\/in\/ramiro-de-rosa--7879a99\/"]},{"@type":"Person","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80","name":"InfoSeguridadIT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","caption":"InfoSeguridadIT"},"sameAs":["https:\/\/infoseguridadit.com\/electronica\/","https:\/\/www.facebook.com\/Infoseguridadit\/","https:\/\/www.instagram.com\/infoseguridadit"],"url":"https:\/\/infoseguridadit.com\/electronica\/author\/ramiroderosa\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/dahua.jpg","jetpack-related-posts":[{"id":14735,"url":"https:\/\/infoseguridadit.com\/electronica\/2023\/11\/18\/dahua-technology-presenta-las-nuevas-pantallas-interactivas-deep-hub\/","url_meta":{"origin":14561,"position":0},"title":"Dahua Technology presenta las nuevas pantallas interactivas Deep Hub.","author":"InfoSeguridadIT","date":"18 de noviembre de 2023","format":false,"excerpt":"Dahua Technology, siempre a la vanguardia en tecnolog\u00eda, presenta las nuevas pantallas interactivas Deep Hub. Dise\u00f1adas y construidas en tama\u00f1os desde las 65\u201d a las 86\u201d, resoluciones de 1080p a 4K, con la calidad a la que Dahua nos tiene acostumbrados, las nuevas pantallas interactivas ofrecen soluciones no solo al\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Captura-de-pantalla-2023-11-29-a-las-10.25.25.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Captura-de-pantalla-2023-11-29-a-las-10.25.25.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Captura-de-pantalla-2023-11-29-a-las-10.25.25.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Captura-de-pantalla-2023-11-29-a-las-10.25.25.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Captura-de-pantalla-2023-11-29-a-las-10.25.25.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Captura-de-pantalla-2023-11-29-a-las-10.25.25.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":15503,"url":"https:\/\/infoseguridadit.com\/electronica\/2024\/07\/18\/videovigilancia-2\/","url_meta":{"origin":14561,"position":1},"title":"Videovigilancia, avances en  2024","author":"InfoSeguridadIT","date":"18 de julio de 2024","format":false,"excerpt":"Videovigilancia, un rubro que ha experimentado avances significativos en los \u00faltimos a\u00f1os. Este art\u00edculo analiza las innovaciones tecnol\u00f3gicas m\u00e1s recientes y c\u00f3mo est\u00e1n mejorando la seguridad y la eficiencia operativa. Innovaciones Tecnol\u00f3gicas: C\u00e1maras con Inteligencia Artificial: La IA permite el an\u00e1lisis en tiempo real y la detecci\u00f3n de comportamientos sospechosos.\u2026","rel":"","context":"En \u00abDestacada\u00bb","block_context":{"text":"Destacada","link":"https:\/\/infoseguridadit.com\/electronica\/category\/destacada\/"},"img":{"alt_text":"videovigilancia","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/07\/instalacion-camara-videovigilancia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/07\/instalacion-camara-videovigilancia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/07\/instalacion-camara-videovigilancia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/07\/instalacion-camara-videovigilancia.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/07\/instalacion-camara-videovigilancia.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/07\/instalacion-camara-videovigilancia.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":9847,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/03\/10\/dahua-technology-lanza-la-camara-full-color-red-la-solucion-wizsense\/","url_meta":{"origin":14561,"position":2},"title":"Dahua Technology lanza la c\u00e1mara Full Color en red de la Soluci\u00f3n WizSense","author":"InfoSeguridadIT","date":"10 de marzo de 2020","format":false,"excerpt":"Dahua Technology, un proveedor l\u00edder mundial de soluciones y servicios de IoT inteligentes centrados en video, lanz\u00f3 con \u00e9xito su nueva soluci\u00f3n para la vigilancia nocturna inteligente: la c\u00e1mara de red WizSense Full-color Series que provee una vigilancia nocturna incomparable impulsada por 4 innovaciones tecnol\u00f3gicas: 1. Lente de gran apertura:\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"dahua-infogremio-2-480x280","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/03\/dahua-infogremio-2-480x280-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10186,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/07\/03\/software-centralizar-monitoreo\/","url_meta":{"origin":14561,"position":3},"title":"Centralizar videovigilancia en distintos lugares del mundo","author":"InfoSeguridadIT","date":"3 de julio de 2020","format":false,"excerpt":"En un contexto donde el control en tiempo real de producto de videovigilancia y monitoreo t\u00e9rmico se vuelven m\u00e1s necesarios que nunca, se lanza un sistema exclusivo que permite controlar estos dispositivos de forma integral, a trav\u00e9s de su cobertura de red global. La gesti\u00f3n de alarmas y monitoreos de\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"dahua","src":"https:\/\/i0.wp.com\/gremioseguridad.com\/electronica\/wp-content\/uploads\/2020\/07\/nuevo-soft-centralizar-monitoreo.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gremioseguridad.com\/electronica\/wp-content\/uploads\/2020\/07\/nuevo-soft-centralizar-monitoreo.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/gremioseguridad.com\/electronica\/wp-content\/uploads\/2020\/07\/nuevo-soft-centralizar-monitoreo.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":9948,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/05\/12\/dahua-2\/","url_meta":{"origin":14561,"position":4},"title":"Dahua Metadata Plugin para Milestone VMS","author":"InfoSeguridadIT","date":"12 de mayo de 2020","format":false,"excerpt":"Dahua Technology es un proveedor l\u00edder mundial de soluciones y servicios de IoT inteligente centrado en video. Basado en innovaciones tecnol\u00f3gicas, Dahua Technology ofrece soluciones, sistemas y servicios de seguridad de extremo a extremo para crear valores para las operaciones de la ciudad, la gesti\u00f3n corporativa y los consumidores. Con\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/infoseguridadit.com\/electronica\/category\/actualidad\/"},"img":{"alt_text":"Dahua y Milestone Infogremio 2","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/05\/Dahua-y-Milestone-Infogremio-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/05\/Dahua-y-Milestone-Infogremio-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/05\/Dahua-y-Milestone-Infogremio-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/05\/Dahua-y-Milestone-Infogremio-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/05\/Dahua-y-Milestone-Infogremio-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":10733,"url":"https:\/\/infoseguridadit.com\/electronica\/2020\/09\/02\/dahua-ia-2\/","url_meta":{"origin":14561,"position":5},"title":"Dahua alcanza m\u00e9tricas hist\u00f3ricas con su tecnolog\u00eda de reconocimiento con IA, en la marcha CASIA-B","author":"InfoSeguridadIT","date":"2 de septiembre de 2020","format":false,"excerpt":"Dahua Technology, un proveedor de servicios y soluciones inteligentes de IoT centrado en video l\u00edder en el mundo, realiz\u00f3 recientemente nuevos avances en el campo de la tecnolog\u00eda de inteligencia artificial. Varios indicadores de su tecnolog\u00eda de reconocimiento de la marcha han batido una vez m\u00e1s el r\u00e9cord del conjunto\u2026","rel":"","context":"En \u00abOpini\u00f3n\u00bb","block_context":{"text":"Opini\u00f3n","link":"https:\/\/infoseguridadit.com\/electronica\/category\/opinion\/"},"img":{"alt_text":"dahua-2-infogremio","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/09\/dahua-2-infogremio.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/09\/dahua-2-infogremio.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/09\/dahua-2-infogremio.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2020\/09\/dahua-2-infogremio.png?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/p6cGtH-3MR","_links":{"self":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/14561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/comments?post=14561"}],"version-history":[{"count":1,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/14561\/revisions"}],"predecessor-version":[{"id":14567,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/14561\/revisions\/14567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media\/14566"}],"wp:attachment":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media?parent=14561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/categories?post=14561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/tags?post=14561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}