{"id":14661,"date":"2023-10-27T08:42:08","date_gmt":"2023-10-27T11:42:08","guid":{"rendered":"https:\/\/infoseguridadit.com\/electronica\/?p=14661"},"modified":"2023-11-08T12:40:12","modified_gmt":"2023-11-08T15:40:12","slug":"ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico","status":"publish","type":"post","link":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/","title":{"rendered":"Ajax present\u00f3 sus nuevas tecnolog\u00edas en un evento \u00fanico"},"content":{"rendered":"\n<p>El&nbsp;quinto Ajax Special Event evidenci\u00f3 la apuesta corporativa por mejorar su&nbsp;gama de productos antiintrusi\u00f3n y antiincendio, con una mayor dedicaci\u00f3n a las soluciones de alta seguridad, a fin de responder las demandas de diversos mercados y a las estrictas normas de la industria.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_presenta_sus_cmaras_impulsadas_por_IA.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_presenta_sus_cmaras_impulsadas_por_IA-1024x577.jpg\" alt=\"\" class=\"wp-image-14662\" srcset=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_presenta_sus_cmaras_impulsadas_por_IA-1024x577.jpg 1024w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_presenta_sus_cmaras_impulsadas_por_IA-300x169.jpg 300w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_presenta_sus_cmaras_impulsadas_por_IA-768x433.jpg 768w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_presenta_sus_cmaras_impulsadas_por_IA.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>C\u00e1maras impulsadas por IA<br><\/strong>Ajax destac\u00f3 que sus referencias TurretCam, BulletCam, y DomeCam Mini utilizan an\u00e1lisis de Inteligencia Artificial para detectar y reconocer varios tipos de objetos, como humanos, veh\u00edculos y animales.<\/p>\n\n\n\n<p>Gracias al servidor Ajax Cloud, estos dispositivos transmiten eventos mientras que la tecnolog\u00eda patentada JetSparrow les permite una r\u00e1pida transmisi\u00f3n de datos de v\u00eddeo peer-to-peer. De esta manera, el sistema graba \u00fanicamente eventos importantes, ahorrando espacio de almacenamiento.<\/p>\n\n\n\n<p>Cada c\u00e1mara se adapta f\u00e1cilmente a los cambios de luz gracias a la tecnolog\u00eda True WDR. Esta tecnolog\u00eda inteligente utiliza un hardware y un software para corregir la iluminaci\u00f3n desigual en escenas complejas, fotograma por fotograma, en tiempo real.<\/p>\n\n\n\n<p>Adem\u00e1s, est\u00e1n equipadas con un micr\u00f3fono digital que utiliza un sistema de reducci\u00f3n de ruido personalizado. cumplen con la protecci\u00f3n IP65 y son capaces de resistir todo tipo de condiciones clim\u00e1ticas. TurretCam, BulletCam, y DomeCam Mini se comercializan con una de cuatro configuraciones posibles, combinando una lente con un \u00e1ngulo de visi\u00f3n de 85 o 110 grados con una resoluci\u00f3n de 3K o 4K.<\/p>\n\n\n\n<p>Ajax NVR se integra con el sistema de gesti\u00f3n de v\u00eddeo (VMS) Ajax, garantizando sincronizaci\u00f3n con el ecosistema Ajax entero y es compatible con la mayor\u00eda de las c\u00e1maras IP. El NVR est\u00e1 disponible en versiones de 8 y 16 canales, y proporciona un acceso instant\u00e1neo al repositorio de v\u00eddeo a trav\u00e9s de la tecnolog\u00eda de transmisi\u00f3n JetSparrow con cifrado TLS.<strong><\/strong><\/p>\n\n\n\n<p><strong>Ecosistema Space<br><\/strong>Space es un entorno virtual que los usuarios pueden crear en la app Ajax. Luego, es posible a\u00f1adir todos los dispositivos necesarios y gestionarlos.<\/p>\n\n\n\n<p>El espacio puede servir de un sistema de seguridad, de videovigilancia o incluso ambos. Su interfaz sigue el concepto de hub Ajax e incluye la pesta\u00f1a de control, las estancias y el acceso r\u00e1pido a los dispositivos de automatizaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/nvr-summary-slide.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/nvr-summary-slide-1024x577.jpg\" alt=\"\" class=\"wp-image-14663\" srcset=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/nvr-summary-slide-1024x577.jpg 1024w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/nvr-summary-slide-300x169.jpg 300w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/nvr-summary-slide-768x433.jpg 768w, https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/nvr-summary-slide.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>Un pad para la gesti\u00f3n avanzada del sistema<br><\/strong>El KeyPad TouchScreen un teclado inal\u00e1mbrico con pantalla t\u00e1ctil, ofrece una interfaz gr\u00e1fica, donde toda la informaci\u00f3n importante est\u00e9 disponible a simple vista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El&nbsp;quinto Ajax Special Event evidenci\u00f3 la apuesta corporativa por mejorar su&nbsp;gama de productos antiintrusi\u00f3n y antiincendio, con una mayor dedicaci\u00f3n a las soluciones de alta seguridad, a fin de responder las demandas de diversos mercados y a las estrictas normas de la industria. C\u00e1maras impulsadas por IAAjax destac\u00f3 que sus referencias TurretCam, BulletCam, y DomeCam [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_joinchat":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[267],"tags":[],"class_list":["post-14661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ajax present\u00f3 sus nuevas tecnolog\u00edas en un evento \u00fanico - InfoSeguridadIT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ajax present\u00f3 sus nuevas tecnolog\u00edas en un evento \u00fanico - InfoSeguridadIT\" \/>\n<meta property=\"og:description\" content=\"El&nbsp;quinto Ajax Special Event evidenci\u00f3 la apuesta corporativa por mejorar su&nbsp;gama de productos antiintrusi\u00f3n y antiincendio, con una mayor dedicaci\u00f3n a las soluciones de alta seguridad, a fin de responder las demandas de diversos mercados y a las estrictas normas de la industria. C\u00e1maras impulsadas por IAAjax destac\u00f3 que sus referencias TurretCam, BulletCam, y DomeCam [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/\" \/>\n<meta property=\"og:site_name\" content=\"InfoSeguridadIT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Infoseguridadit\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-27T11:42:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-08T15:40:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_-_Rule_Your_Space.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"InfoSeguridadIT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:site\" content=\"@gremioseguridad\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"InfoSeguridadIT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/\"},\"author\":{\"name\":\"InfoSeguridadIT\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\"},\"headline\":\"Ajax present\u00f3 sus nuevas tecnolog\u00edas en un evento \u00fanico\",\"datePublished\":\"2023-10-27T11:42:08+00:00\",\"dateModified\":\"2023-11-08T15:40:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/\"},\"wordCount\":424,\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ajax_-_Rule_Your_Space.jpg\",\"articleSection\":[\"Informes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/\",\"name\":\"Ajax present\u00f3 sus nuevas tecnolog\u00edas en un evento \u00fanico - InfoSeguridadIT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ajax_-_Rule_Your_Space.jpg\",\"datePublished\":\"2023-10-27T11:42:08+00:00\",\"dateModified\":\"2023-11-08T15:40:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ajax_-_Rule_Your_Space.jpg\",\"contentUrl\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ajax_-_Rule_Your_Space.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Ajax_-_Rule_Your_Space\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/2023\\\/10\\\/27\\\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ajax present\u00f3 sus nuevas tecnolog\u00edas en un evento \u00fanico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#website\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"name\":\"InfoSeguridadIT\",\"description\":\"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.\",\"publisher\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#organization\",\"name\":\"InfoSeguridadIT\",\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"contentUrl\":\"http:\\\/\\\/infoseguridadit.com\\\/electronica\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-logo-isit-latam-low-b.png\",\"width\":400,\"height\":111,\"caption\":\"InfoSeguridadIT\"},\"image\":{\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\",\"https:\\\/\\\/x.com\\\/gremioseguridad\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ramiro-de-rosa--7879a99\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/#\\\/schema\\\/person\\\/ebbcebab56199bc170ca93cc17e06b80\",\"name\":\"InfoSeguridadIT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g\",\"caption\":\"InfoSeguridadIT\"},\"sameAs\":[\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/\",\"https:\\\/\\\/www.facebook.com\\\/Infoseguridadit\\\/\",\"https:\\\/\\\/www.instagram.com\\\/infoseguridadit\"],\"url\":\"https:\\\/\\\/infoseguridadit.com\\\/electronica\\\/author\\\/ramiroderosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ajax present\u00f3 sus nuevas tecnolog\u00edas en un evento \u00fanico - InfoSeguridadIT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/","og_locale":"es_ES","og_type":"article","og_title":"Ajax present\u00f3 sus nuevas tecnolog\u00edas en un evento \u00fanico - InfoSeguridadIT","og_description":"El&nbsp;quinto Ajax Special Event evidenci\u00f3 la apuesta corporativa por mejorar su&nbsp;gama de productos antiintrusi\u00f3n y antiincendio, con una mayor dedicaci\u00f3n a las soluciones de alta seguridad, a fin de responder las demandas de diversos mercados y a las estrictas normas de la industria. C\u00e1maras impulsadas por IAAjax destac\u00f3 que sus referencias TurretCam, BulletCam, y DomeCam [&hellip;]","og_url":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/","og_site_name":"InfoSeguridadIT","article_publisher":"https:\/\/www.facebook.com\/Infoseguridadit","article_author":"https:\/\/www.facebook.com\/Infoseguridadit\/","article_published_time":"2023-10-27T11:42:08+00:00","article_modified_time":"2023-11-08T15:40:12+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_-_Rule_Your_Space.jpg","type":"image\/jpeg"}],"author":"InfoSeguridadIT","twitter_card":"summary_large_image","twitter_creator":"@gremioseguridad","twitter_site":"@gremioseguridad","twitter_misc":{"Escrito por":"InfoSeguridadIT","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/#article","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/"},"author":{"name":"InfoSeguridadIT","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80"},"headline":"Ajax present\u00f3 sus nuevas tecnolog\u00edas en un evento \u00fanico","datePublished":"2023-10-27T11:42:08+00:00","dateModified":"2023-11-08T15:40:12+00:00","mainEntityOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/"},"wordCount":424,"publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_-_Rule_Your_Space.jpg","articleSection":["Informes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/","url":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/","name":"Ajax present\u00f3 sus nuevas tecnolog\u00edas en un evento \u00fanico - InfoSeguridadIT","isPartOf":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/#primaryimage"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/#primaryimage"},"thumbnailUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_-_Rule_Your_Space.jpg","datePublished":"2023-10-27T11:42:08+00:00","dateModified":"2023-11-08T15:40:12+00:00","breadcrumb":{"@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/#primaryimage","url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_-_Rule_Your_Space.jpg","contentUrl":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_-_Rule_Your_Space.jpg","width":1200,"height":630,"caption":"Ajax_-_Rule_Your_Space"},{"@type":"BreadcrumbList","@id":"https:\/\/infoseguridadit.com\/electronica\/2023\/10\/27\/ayax-presento-sus-nuevas-tecnologias-en-un-evento-unico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/infoseguridadit.com\/electronica\/"},{"@type":"ListItem","position":2,"name":"Ajax present\u00f3 sus nuevas tecnolog\u00edas en un evento \u00fanico"}]},{"@type":"WebSite","@id":"https:\/\/infoseguridadit.com\/electronica\/#website","url":"https:\/\/infoseguridadit.com\/electronica\/","name":"InfoSeguridadIT","description":"InfoSeguridadIT es un portal de noticias sobre tecnolog\u00eda y seguridad electr\u00f3nica dirigido a Integradores, Distribuidores, Importadores, Fabricantes, etc.","publisher":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoseguridadit.com\/electronica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infoseguridadit.com\/electronica\/#organization","name":"InfoSeguridadIT","url":"https:\/\/infoseguridadit.com\/electronica\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/","url":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","contentUrl":"http:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/cropped-logo-isit-latam-low-b.png","width":400,"height":111,"caption":"InfoSeguridadIT"},"image":{"@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Infoseguridadit","https:\/\/x.com\/gremioseguridad","https:\/\/www.instagram.com\/infoseguridadit\/","https:\/\/www.linkedin.com\/in\/ramiro-de-rosa--7879a99\/"]},{"@type":"Person","@id":"https:\/\/infoseguridadit.com\/electronica\/#\/schema\/person\/ebbcebab56199bc170ca93cc17e06b80","name":"InfoSeguridadIT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f65dac9718ad877804b6a3fb5a58ca3238715fb7957e908f214fc5d6161d758f?s=96&d=mm&r=g","caption":"InfoSeguridadIT"},"sameAs":["https:\/\/infoseguridadit.com\/electronica\/","https:\/\/www.facebook.com\/Infoseguridadit\/","https:\/\/www.instagram.com\/infoseguridadit"],"url":"https:\/\/infoseguridadit.com\/electronica\/author\/ramiroderosa\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/10\/Ajax_-_Rule_Your_Space.jpg","jetpack-related-posts":[{"id":14497,"url":"https:\/\/infoseguridadit.com\/electronica\/2023\/08\/10\/fullcenter-y-fullarm-de-fulltime-son-ahora-compatibles-con-los-productos-ajax\/","url_meta":{"origin":14661,"position":0},"title":"FullCenter y FullArm de FullTime son ahora compatibles con los productos Ajax","author":"InfoSeguridadIT","date":"10 de agosto de 2023","format":false,"excerpt":"Nos complace anunciar una alianza entre Ajax Systems, el sistema de seguridad m\u00e1s premiado en Europa y FullTime, una empresa l\u00edder especializada en el desarrollo de soluciones en la nube para las empresas de monitoreo y rastreo. Esta alianza ha dado lugar a una integraci\u00f3n excepcional entre la alarma Ajax\u2026","rel":"","context":"En \u00abInformes\u00bb","block_context":{"text":"Informes","link":"https:\/\/infoseguridadit.com\/electronica\/category\/inf\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/08\/INTEGRATION-Fulltime-Latam-preview-2x-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/08\/INTEGRATION-Fulltime-Latam-preview-2x-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/08\/INTEGRATION-Fulltime-Latam-preview-2x-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/08\/INTEGRATION-Fulltime-Latam-preview-2x-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/08\/INTEGRATION-Fulltime-Latam-preview-2x-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/08\/INTEGRATION-Fulltime-Latam-preview-2x-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":14082,"url":"https:\/\/infoseguridadit.com\/electronica\/2023\/05\/20\/ajax-2\/","url_meta":{"origin":14661,"position":1},"title":"Ajax se integra con el software de monitorizaci\u00f3n de Bykom","author":"InfoSeguridadIT","date":"20 de mayo de 2023","format":false,"excerpt":"Ajax da otro gran paso en su expansi\u00f3n en Latinoam\u00e9rica con la integraci\u00f3n con Bykom. Desde este momento, el software de Bykom puede recibir las fotoverificaciones de alarmas desde los detectores inal\u00e1mbricos MotionCam y MotionCam Outdoor, optimizando as\u00ed la gesti\u00f3n del monitoreo. C\u00f3mo funciona Los dispositivos de Ajax se conectan\u2026","rel":"","context":"En \u00abInformes\u00bb","block_context":{"text":"Informes","link":"https:\/\/infoseguridadit.com\/electronica\/category\/inf\/"},"img":{"alt_text":"ajax","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/ByKom_preview-2x.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/ByKom_preview-2x.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/ByKom_preview-2x.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/ByKom_preview-2x.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/ByKom_preview-2x.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/03\/ByKom_preview-2x.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":15959,"url":"https:\/\/infoseguridadit.com\/electronica\/2025\/11\/11\/ajax\/","url_meta":{"origin":14661,"position":2},"title":"Ajax Systems inaugura una nueva f\u00e1brica en Vietnam y refuerza su expansi\u00f3n global","author":"InfoSeguridadIT","date":"11 de noviembre de 2025","format":false,"excerpt":"Ajax Systems, empresa internacional de tecnolog\u00eda y fabricante l\u00edder de sistemas de seguridad profesionales, anunci\u00f3 la inauguraci\u00f3n de una nueva f\u00e1brica en Han\u00f3i, Vietnam, consolidando as\u00ed un paso clave en su estrategia de expansi\u00f3n y diversificaci\u00f3n global. La nueva planta, de 8.300 metros cuadrados, producir\u00e1 la gama completa de dispositivos\u2026","rel":"","context":"En \u00abDestacada\u00bb","block_context":{"text":"Destacada","link":"https:\/\/infoseguridadit.com\/electronica\/category\/destacada\/"},"img":{"alt_text":"ajax","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2025\/11\/ajax.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2025\/11\/ajax.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2025\/11\/ajax.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2025\/11\/ajax.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2025\/11\/ajax.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2025\/11\/ajax.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":14374,"url":"https:\/\/infoseguridadit.com\/electronica\/2023\/06\/09\/ajax-cmc\/","url_meta":{"origin":14661,"position":3},"title":"Ajax Systems se asocia con CMC Alarmas en Argentina","author":"InfoSeguridadIT","date":"9 de junio de 2023","format":false,"excerpt":"Ajax da otro paso importante en su expansi\u00f3n en Argentina al asociarse con\u00a0CMC Alarmas. A partir de ahora, el software de CMC puede recibir alarmas y verificaciones fotogr\u00e1ficas del sistema de seguridad Ajax. CMC Alarmas utiliza su software de monitoreo profesional, el cual est\u00e1 integrado con Ajax a trav\u00e9s de\u2026","rel":"","context":"En \u00abInformes\u00bb","block_context":{"text":"Informes","link":"https:\/\/infoseguridadit.com\/electronica\/category\/inf\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/07\/cms-alarmas-ajax-infoseguridadit.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/07\/cms-alarmas-ajax-infoseguridadit.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/07\/cms-alarmas-ajax-infoseguridadit.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/07\/cms-alarmas-ajax-infoseguridadit.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/07\/cms-alarmas-ajax-infoseguridadit.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/07\/cms-alarmas-ajax-infoseguridadit.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":14731,"url":"https:\/\/infoseguridadit.com\/electronica\/2023\/11\/28\/ajax-systems-refuerza-su-presencia-en-peru-asociandose-con-liderman\/","url_meta":{"origin":14661,"position":4},"title":"Ajax Systems refuerza su presencia en Per\u00fa asoci\u00e1ndose con Liderman","author":"InfoSeguridadIT","date":"28 de noviembre de 2023","format":false,"excerpt":"Ajax Systems, el mayor desarrollador y fabricante europeo de sistemas de seguridad, se enorgullece de anunciar una alianza estrat\u00e9gica con\u00a0Liderman, una empresa peruana l\u00edder en seguridad. Esta colaboraci\u00f3n representa el firme compromiso de Ajax de aportar soluciones de seguridad de nivel superior en todo el mundo. El robusto software de\u2026","rel":"","context":"En \u00abInformes\u00bb","block_context":{"text":"Informes","link":"https:\/\/infoseguridadit.com\/electronica\/category\/inf\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Liderman-Peru_ajax.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Liderman-Peru_ajax.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Liderman-Peru_ajax.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Liderman-Peru_ajax.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Liderman-Peru_ajax.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2023\/11\/Liderman-Peru_ajax.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":15308,"url":"https:\/\/infoseguridadit.com\/electronica\/2024\/05\/24\/ajax-systems\/","url_meta":{"origin":14661,"position":5},"title":"Ajax Systems gana su primer premio Red Dot Award por tres productos de seguridad y de dom\u00f3tica","author":"InfoSeguridadIT","date":"24 de mayo de 2024","format":false,"excerpt":"Ajax Systems se complace en anunciar que ha ganado el prestigioso premio\u00a0Red Dot Award\u00a0por primera vez en la historia de la empresa. Este a\u00f1o, los productos antiintrusi\u00f3n y de dom\u00f3tica Ajax recibieron el reconocimiento en las siguientes categor\u00edas: Categor\u00eda de Productos inteligentes: KeyPad TouchScreen Jeweller; Categor\u00eda de Elementos de dise\u00f1o\u2026","rel":"","context":"En \u00abIntrusi\u00f3n\u00bb","block_context":{"text":"Intrusi\u00f3n","link":"https:\/\/infoseguridadit.com\/electronica\/category\/intrusion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/05\/ajax-systems.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/05\/ajax-systems.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/05\/ajax-systems.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/05\/ajax-systems.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/infoseguridadit.com\/electronica\/wp-content\/uploads\/2024\/05\/ajax-systems.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/p6cGtH-3Ot","_links":{"self":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/14661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/comments?post=14661"}],"version-history":[{"count":2,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/14661\/revisions"}],"predecessor-version":[{"id":14671,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/posts\/14661\/revisions\/14671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media\/14664"}],"wp:attachment":[{"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/media?parent=14661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/categories?post=14661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoseguridadit.com\/electronica\/wp-json\/wp\/v2\/tags?post=14661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}